{"id":103648,"date":"2022-02-03T23:59:00","date_gmt":"2022-02-04T02:59:00","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=103648"},"modified":"2022-02-04T00:17:41","modified_gmt":"2022-02-04T03:17:41","slug":"letra-intensamente-di-ferrero-vitor-kley","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/letra-intensamente-di-ferrero-vitor-kley\/","title":{"rendered":"Letra de &#8220;Intensamente&#8221; &#8211; Di Ferrero, Vitor Kley"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Artista: <strong><a href=\"http:\/\/instagram.com\/portalpopmais\" target=\"_blank\" rel=\"noopener\">Di Ferrero,<\/a> Vitor Kley<\/strong><br>M\u00fasica: Intensamente<br>Lan\u00e7amento: <a href=\"http:\/\/portalpopmais.com.br\/en\/\">3 de fevereiro de 2022<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"INTENSAMENTE\" width=\"880\" height=\"660\" src=\"https:\/\/www.youtube.com\/embed\/Vw8EYd5Jvok?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Letra<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Diga o que seus olhos querem, deixa eu te mostrar meu mundo<br>Que o tempo escorre pelos dedos, meu amor, a vida \u00e9 t\u00e3o rara<br>Bota f\u00e9 nas coisas, isso j\u00e1 diz muita coisa<br>E, se permitir sonhar tem que ser um mantra<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pra sentir o sol<br>Num dia quente<br>Deixa eu ter voc\u00ea<br>Intensamente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pra sentir o sol<br>Num dia quente<br>Deixa eu ter voc\u00ea<br>Intensamente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Intensamente<br>Intensamente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diga o que seus olhos querem e fa\u00e7a desse dia um sonho<br>Vale a pena se jogar no mundo, baby, a vida \u00e9 t\u00e3o rara<br>Bota f\u00e9 nas coisas, isso j\u00e1 diz muita coisa<br>Te levar pra casa, agora \u00e9 meu novo mantra<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pra sentir o sol<br>Num dia quente<br>Deixa eu ter voc\u00ea<br>Intensamente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pra sentir o sol<br>Num dia quente<br>Deixa eu ter voc\u00ea<br>Intensamente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pra sentir o sol<br>Num dia quente<br>Deixa eu ter voc\u00ea<br>Intensamente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Intensamente<br>Intensamente<\/p>","protected":false},"excerpt":{"rendered":"<p>Artista: Di Ferrero, Vitor KleyM\u00fasica: IntensamenteLan\u00e7amento: 3 de fevereiro de 2022 Letra Diga o que seus olhos querem, deixa eu te mostrar meu mundoQue o tempo escorre pelos dedos, meu amor, a vida \u00e9 t\u00e3o raraBota f\u00e9 nas coisas, isso j\u00e1 diz muita coisaE, se permitir sonhar tem que ser um mantra Pra sentir o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":103649,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[422,8166,785],"class_list":["post-103648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fire2","tag-di-ferrero","tag-letras","tag-vitor-kley"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/103648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=103648"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/103648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/103649"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=103648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=103648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=103648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}