{"id":115320,"date":"2022-05-05T08:25:08","date_gmt":"2022-05-05T11:25:08","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=115320"},"modified":"2022-05-05T09:15:03","modified_gmt":"2022-05-05T12:15:03","slug":"aposentadoria-saiba-ate-quando-vai-o-contrato-de-william-bonner-e-renata-vasconcellos-e-quanto-ganha-cada-um","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/aposentadoria-saiba-ate-quando-vai-o-contrato-de-william-bonner-e-renata-vasconcellos-e-quanto-ganha-cada-um\/","title":{"rendered":"Aposentadoria? Veja at\u00e9 quando vai os contratos de William Bonner e Renata Vasconcellos e seus sal\u00e1rios"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Os apresentadores do \u201cJornal Nacional\u201d, William Bonner e Renata Vasconcellos, j\u00e1 tem um novo prazo para o fim do contrato com a Globo. Quebrando muitas expectativas, principalmente por Willliam, a parceria n\u00e3o vai terminar t\u00e3o cedo assim.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As informa\u00e7\u00f5es obtidas pelo site Observat\u00f3rio da TV, s\u00e3o de que ambos tiveram contrato renovado com a Globo at\u00e9 2025. E tamb\u00e9m n\u00e3o \u00e9 para menos, tendo em vista do quanto ganha cada um, sendo titulares do jornal mais assistido da TV aberta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre grandes nomes do jornalismo feminino, como Sandra Annenberg, Maju Coutinho, Gloria Maria e Poliana Abritta, o de Renata \u00e9 destaque quanto ao quesito sal\u00e1rio. A estimativa \u00e9 que os vencimentos da \u00e2ncora do principal telejornal da casa receba em torno de R$ 400 mil. E Bonner na condi\u00e7\u00e3o de editor-chefe, todos os meses a Globo paga R$ 900 mil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>E Bonner n\u00e3o iria aposentar?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa era a expectativa de muitos, sendo quebrada pela renova\u00e7\u00e3o do contrato com exclusividade para a TV Globo. A suspeita aumentou quando foi divulgada a informa\u00e7\u00e3o de que Bonner n\u00e3o queria mediar debates este ano.<\/p>","protected":false},"excerpt":{"rendered":"<p>Os apresentadores do \u201cJornal Nacional\u201d, William Bonner e Renata Vasconcellos, j\u00e1 tem um novo prazo para o fim do contrato com a Globo. Quebrando muitas expectativas, principalmente por Willliam, a parceria n\u00e3o vai terminar t\u00e3o cedo assim. As informa\u00e7\u00f5es obtidas pelo site Observat\u00f3rio da TV, s\u00e3o de que ambos tiveram contrato renovado com a Globo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":115321,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[181],"tags":[1434,8662,1435],"class_list":["post-115320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-televisao","tag-jornal-nacional","tag-renata-vasconcellos","tag-william-bonner"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/115320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=115320"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/115320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/115321"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=115320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=115320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=115320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}