{"id":119507,"date":"2022-06-03T12:26:38","date_gmt":"2022-06-03T15:26:38","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=119507"},"modified":"2022-06-03T12:26:43","modified_gmt":"2022-06-03T15:26:43","slug":"shakira-socorrida-ambulancia-apos-separacao","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/shakira-socorrida-ambulancia-apos-separacao\/","title":{"rendered":"Shakira \u00e9 socorrida \u00e0s pressas em ambul\u00e2ncia ap\u00f3s separa\u00e7\u00e3o de Piqu\u00e9"},"content":{"rendered":"<p>A not\u00edcia sobre a separa\u00e7\u00e3o de <strong><a href=\"https:\/\/portalpopmais.com.br\/en\/chega-ao-fim-o-casamento-de-shakira-e-gerard-pique-diz-imprensa-espanhola\/\" data-type=\"post\" data-id=\"119160\">Shakira<\/a><\/strong> e <strong><a href=\"http:\/\/instagram.com\/portalpopmais\" target=\"_blank\" rel=\"noopener\">Piqu\u00e9<\/a><\/strong> segue rendendo. Agora, outro acontecimento veio a tona. O portal espanhol HOLA! detalha que uma ambul\u00e2ncia foi vista socorrendo a cantora, no \u00faltimo s\u00e1bado (28).<\/p>\n\n\n\n<p>O epis\u00f3dio teria ocorrido dias antes do El Peri\u00f3dico detalhar a suposta separa\u00e7\u00e3o do casal. De acordo com as informa\u00e7\u00f5es da publica\u00e7\u00e3o, foram vistos dois carros e uma ambul\u00e2ncia pr\u00f3ximos \u00e0 resid\u00eancia de Shakira e Piqu\u00e9, em Barcelona.<\/p>\n\n\n\n<p>O relacionamento dos famosos teria chegado ao fim ap\u00f3s Shakira descobrir uma trai\u00e7\u00e3o de Piqu\u00e9. Veja detalhes <a href=\"https:\/\/portalpopmais.com.br\/en\/chega-ao-fim-o-casamento-de-shakira-e-gerard-pique-diz-imprensa-espanhola\/\" target=\"_blank\" data-type=\"post\" data-id=\"119160\" rel=\"noreferrer noopener\">aqui<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Shakira precisa ser socorrida<\/h2>\n\n\n\n<p>De acordo com o site espanhol, Shakira parecia estar bastante abalada, como informaram fontes pr\u00f3ximas ao local. Com crises de choro e ansiedade, a cantora precisou ser socorrida.<\/p>\n\n\n\n<p>Piqu\u00e9, por sua vez, tamb\u00e9m estava no local, bastante nervoso e aguardando o que aconteceria a seguir.<\/p>\n\n\n\n<p>Shakira, ent\u00e3o, teria pedido para ser levada a uma cl\u00ednica, e se sentou no banco do passageiro da ambul\u00e2ncia. Piqu\u00e9 ainda tentou acalmar a ent\u00e3o esposa com um grande abra\u00e7o, e seguiu at\u00e9 a tal unidade, que tamb\u00e9m fica em Barcelona.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que aconteceu com Shakira?<\/h2>\n\n\n\n<p>Ainda segundo testemunhas, n\u00e3o houve nenhum acidente ou tipo de evento relacionado para que houvesse uma ambul\u00e2ncia no local. Tamb\u00e9m n\u00e3o se sabe o que causou a crise de ansiedade de Shakira.<\/p>\n\n\n\n<p>At\u00e9 a publica\u00e7\u00e3o desta mat\u00e9ria, a equipe de comunica\u00e7\u00e3o da cantora colombiana n\u00e3o se manifestou sobre o caso. <\/p>","protected":false},"excerpt":{"rendered":"<p>A not\u00edcia sobre a separa\u00e7\u00e3o de Shakira e Piqu\u00e9 segue rendendo. Agora, outro acontecimento veio a tona. O portal espanhol HOLA! detalha que uma ambul\u00e2ncia foi vista socorrendo a cantora, no \u00faltimo s\u00e1bado (28). O epis\u00f3dio teria ocorrido dias antes do El Peri\u00f3dico detalhar a suposta separa\u00e7\u00e3o do casal. De acordo com as informa\u00e7\u00f5es da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":119509,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[466],"class_list":["post-119507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-shakira"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/119507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=119507"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/119507\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/119509"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=119507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=119507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=119507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}