{"id":134585,"date":"2022-08-29T10:33:42","date_gmt":"2022-08-29T13:33:42","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=134585"},"modified":"2022-08-29T10:33:46","modified_gmt":"2022-08-29T13:33:46","slug":"fora-do-encontro-manoel-soares-abre-o-jogo-sobre-planos-de-deixar-a-globo-vender-pao-de-queijo","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/fora-do-encontro-manoel-soares-abre-o-jogo-sobre-planos-de-deixar-a-globo-vender-pao-de-queijo\/","title":{"rendered":"Fora do &#8220;Encontro&#8221;? Manoel Soares abre o jogo sobre planos de deixar a Globo: &#8220;Vender p\u00e3o de queijo&#8221;"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Companheiro de Patr\u00edcia Poeta no comando do &#8220;Encontro&#8221;, o apresentador <strong><a href=\"https:\/\/portalpopmais.com.br\/en\/patricia-poeta-cara-desprazer-manoel-soares\/\" target=\"_blank\" data-type=\"post\" data-id=\"132176\" rel=\"noreferrer noopener\">Manoel Soares<\/a><\/strong> foi \u00e0s redes sociais se pronunciar sobre os rumores de que estaria deixando o programa. Os boatos d\u00e3o conta que rola um clim\u00e3o entre os dois nos bastidores do matinal e que a sa\u00edda do comunicador \u00e9 quase certa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acontece que, v\u00e1rios telespectadores e f\u00e3s do \u201cEncontro\u201d pediram para Manoel sair da atra\u00e7\u00e3o como forma de preservar sua imagem Isso porque Poeta tem recebido cr\u00edticas por conta de sua postura com Manoel. V\u00e1rios internautas apontam que ela tenta diminuir a participa\u00e7\u00e3o do colega na <a href=\"http:\/\/instagram.com\/portalpopmais\" target=\"_blank\" rel=\"noopener\">atra\u00e7\u00e3o<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Veja tamb\u00e9m<\/h2>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 aligncenter wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/casa-de-lamine-yamal-em-barcelona-e-alvo-de-tentativa-de-roubo\/\" aria-label=\"Casa de Lamine Yamal, em Barcelona, \u00e9 alvo de tentativa de roubo\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/spain-v-belgium-quarter-final-fifa-world-cup-2026-7-1-768x456.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"spain v belgium quarter final fifa world cup 2026 7 1\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/spain-v-belgium-quarter-final-fifa-world-cup-2026-7-1-768x456.jpg 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/spain-v-belgium-quarter-final-fifa-world-cup-2026-7-1-1170x694.jpg 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/spain-v-belgium-quarter-final-fifa-world-cup-2026-7-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/casa-de-lamine-yamal-em-barcelona-e-alvo-de-tentativa-de-roubo\/\">Casa de Lamine Yamal, em Barcelona, \u00e9 alvo de tentativa de roubo<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/saiba-o-valor-da-heranca-deixada-por-daveigh-chase-atriz-de-o-chamado-que-morreu-aos-35-anos\/\" aria-label=\"Saiba o valor da heran\u00e7a deixada por Daveigh Chase, atriz de &#8216;O Chamado&#8217; que morreu aos 35 anos\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/causa-morte-Daveigh-Chase-768x456.avif\" class=\"attachment-medium size-medium wp-post-image\" alt=\"causa morte Daveigh Chase\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/causa-morte-Daveigh-Chase-768x456.avif 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/causa-morte-Daveigh-Chase-1170x694.avif 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/causa-morte-Daveigh-Chase-18x10.avif 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/saiba-o-valor-da-heranca-deixada-por-daveigh-chase-atriz-de-o-chamado-que-morreu-aos-35-anos\/\">Saiba o valor da heran\u00e7a deixada por Daveigh Chase, atriz de &#8216;O Chamado&#8217; que morreu aos 35 anos<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/virginia-compra-apartamento-milionario-em-predio-de-neymar\/\" aria-label=\"Virginia compra apartamento milion\u00e1rio em pr\u00e9dio de Neymar\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"mp investiga blaze contratos neymar virginia\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-1170x694.png 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-18x12.png 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/virginia-compra-apartamento-milionario-em-predio-de-neymar\/\">Virginia compra apartamento milion\u00e1rio em pr\u00e9dio de Neymar<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/cartolouco-se-pronuncia-contesta-acusacoes-de-agressao-e-rebate-ex-veja-o-video\/\" aria-label=\"Cartolouco se pronuncia, contesta acusa\u00e7\u00f5es de agress\u00e3o e rebate ex; veja o v\u00eddeo\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2020\/12\/Design-sem-nome-23-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Lucas Cartolouco para Rede Record\" style=\"\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/cartolouco-se-pronuncia-contesta-acusacoes-de-agressao-e-rebate-ex-veja-o-video\/\">Cartolouco se pronuncia, contesta acusa\u00e7\u00f5es de agress\u00e3o e rebate ex; veja o v\u00eddeo<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/homem-processa-virginia-e-outros-influencers-apos-perder-r-100-mil-em-bets\/\" aria-label=\"Homem processa Virginia e outros influenciadores ap\u00f3s perder R$ 100 mil em bets\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/02\/virginia-passa-mal-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Virginia Fonseca - Foto: Reprodu\u00e7\u00e3o Instagram\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/02\/virginia-passa-mal-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/02\/virginia-passa-mal-1170x694.png 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/02\/virginia-passa-mal-18x10.png 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/homem-processa-virginia-e-outros-influencers-apos-perder-r-100-mil-em-bets\/\">Homem processa Virginia e outros influenciadores ap\u00f3s perder R$ 100 mil em bets<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/casamento-de-ryan-gosling-e-eva-mendes-enfrenta-momento-delicado-diz-site\/\" aria-label=\"Casamento de Ryan Gosling e Eva Mendes enfrenta momento delicado, diz site\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/Ryan-Gosling-e-Eva-Mendes-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Ryan Gosling e Eva Mendes\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/Ryan-Gosling-e-Eva-Mendes-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/Ryan-Gosling-e-Eva-Mendes-18x10.png 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/casamento-de-ryan-gosling-e-eva-mendes-enfrenta-momento-delicado-diz-site\/\">Casamento de Ryan Gosling e Eva Mendes enfrenta momento delicado, diz site<\/a><\/li>\n<\/ul>\n\n\n<p class=\"wp-block-paragraph\"> Uma f\u00e3 de Manoel chegou a dizer que Patr\u00edcia est\u00e1: \u201cdesesperada querendo falar tudo todo tempo e voc\u00ea ali, parecendo que est\u00e1 cumprindo cota para o programa\u201c. No entanto, Manoel se manifestou e abriu o jogo sobre sair do programa:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">Gente, n\u00e3o pedi para sair.<br>Isso n\u00e3o \u00e9 verdade.\u270a\ud83c\udffe\u270a\ud83c\udffe\ud83d\udcaa\ud83c\udffe\ud83d\udcaa\ud83c\udffe<\/p>&mdash; Manoel Soares (@ManoelSoares_) <a href=\"https:\/\/twitter.com\/ManoelSoares_\/status\/1563626815469527043?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">August 27, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Manoel Soares quase pediu demiss\u00e3o da Globo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Durante sua participa\u00e7\u00e3o na edi\u00e7\u00e3o especial do \u201cPodPah\u201d para o crian\u00e7a esperan\u00e7a, o apresentador da Globo, Manoel Soares admitiu que planejava pedir demiss\u00e3o da emissora para abrir um neg\u00f3cio de venda de p\u00e3o de queijo. No papo, o jornalista disse que a vontade do novo empreendimento se deu pois estava estagnado financeiramente na carreira. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cTrabalhava em uma TV no Rio Grande do Sul, j\u00e1 estava l\u00e1 h\u00e1 uns 15 anos, sal\u00e1rio de afiliada, n\u00e9? N\u00e3o era um brilho. Cheguei para a nega e falei assim: \u2018Vamos fazer uma franquia de p\u00e3o de queijo, que acho que o nosso futuro est\u00e1 no p\u00e3o de queijo\u2018. Precisava de uma grana inicial, que seria a rescis\u00e3o\u201d<\/em>, relembrou o apresentador. <em>\u201cEstava h\u00e1 anos , j\u00e1 era o rep\u00f3rter, n\u00e3o tinha mais o que fazer. Sabe quando voc\u00ea d\u00e1 o estalo, quer mudar de vida? Meu chefe falou: \u2018Neg\u00e3o, voc\u00ea est\u00e1 viajando, tem um futuro pela frente, voc\u00ea \u00e9 um comunicador, s\u00f3 est\u00e1 ansioso\u2018\u201d<\/em>, contou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, o ent\u00e3o chefe de Manoel o escalou para uma entrada ao vivo no &#8220;Encontro com F\u00e1tima Bernardes&#8221; e o jornalista come\u00e7ou a ganhar proje\u00e7\u00e3o em escala nacional.<em> \u201cA F\u00e1tima falou: \u2018Quero que voc\u00ea venha trabalhar comigo\u2018. Nem entendi quando ela falou. O Mauricio Arruda, que era diretor do programa, botou uma f\u00e9, come\u00e7ou uma transa\u00e7\u00e3o. Quatro meses depois, estava aqui na Globo, com o olho arregalado, olhando para a cara dela, que disse: \u2018Que bom que voc\u00ea est\u00e1 aqui\u2018\u201d,<\/em> comentou.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.instagram.com\/p\/CfegFoJrR_C\/\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Companheiro de Patr\u00edcia Poeta no comando do &#8220;Encontro&#8221;, o apresentador Manoel Soares foi \u00e0s redes sociais se pronunciar sobre os rumores de que estaria deixando o programa. Os boatos d\u00e3o conta que rola um clim\u00e3o entre os dois nos bastidores do matinal e que a sa\u00edda do comunicador \u00e9 quase certa. Acontece que, v\u00e1rios telespectadores [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":134587,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[181],"tags":[10802],"class_list":["post-134585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-televisao","tag-manoel-soares"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/134585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=134585"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/134585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/134587"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=134585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=134585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=134585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}