{"id":139902,"date":"2022-09-23T07:47:40","date_gmt":"2022-09-23T10:47:40","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=139902"},"modified":"2022-09-23T07:48:59","modified_gmt":"2022-09-23T10:48:59","slug":"ratinho-faz-pergunta-indiscreta-ao-entrevistar-lula-no-sbt-vai-proibir-de-ver-sacanagem","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/ratinho-faz-pergunta-indiscreta-ao-entrevistar-lula-no-sbt-vai-proibir-de-ver-sacanagem\/","title":{"rendered":"Ratinho faz pergunta indiscreta para Lula: &#8220;Vai proibir de ver sacanagem?&#8221;"},"content":{"rendered":"<p>Nesta quinta-feira (22), <strong><a href=\"https:\/\/portalpopmais.com.br\/en\/assessores-lula-ciro-batem-boca-reuniao-globo\/\" data-type=\"post\" data-id=\"138066\">Lula<\/a><\/strong> esteve com <strong><a href=\"http:\/\/Instagram.com\" target=\"_blank\" rel=\"noopener\">Ratinho<\/a><\/strong>, como partes das entrevistas promovidas pelo SBT com presidenci\u00e1veis. Por\u00e9m, durante a conversa, uma pergunta inusitada acabou pegando o candidato de surpresa ao lhe questionar sobre uma poss\u00edvel censura do porn\u00f4 caso ganhe as elei\u00e7\u00f5es.<\/p>\n\n\n\n<p>O assunto veio \u00e0 tona quando o apresentador comentou sobre a regulamenta\u00e7\u00e3o da m\u00eddia. &#8220;Vai proibir o povo de ver sacanagem ou o meu programa?&#8221;, quis saber o contratado de Silvio Santos. &#8220;N\u00e3o, eu quero que seu programa tenha ainda muito mais edi\u00e7\u00f5es&#8221;, respondeu o pol\u00edtico.<\/p>\n\n\n\n<p>Em seguida, Lula acrescentou: &#8220;N\u00f3s fizemos uma confer\u00eancia em 2009 e participaram mais de 3 mil pessoas, incluindo representantes de emissoras de TV. Voc\u00ea n\u00e3o pode censurar revista, jornal, mas pode fazer com que sejam regulados de acordo com os interesses da sociedade. A \u00faltima reforma foi em 1962. Do tempo de Pel\u00e9. Temos que nos adaptar&#8221;.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nesta quinta-feira (22), Lula esteve com Ratinho, como partes das entrevistas promovidas pelo SBT com presidenci\u00e1veis. Por\u00e9m, durante a conversa, uma pergunta inusitada acabou pegando o candidato de surpresa ao lhe questionar sobre uma poss\u00edvel censura do porn\u00f4 caso ganhe as elei\u00e7\u00f5es. O assunto veio \u00e0 tona quando o apresentador comentou sobre a regulamenta\u00e7\u00e3o da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":139905,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[181],"tags":[6418,642],"class_list":["post-139902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-televisao","tag-lula","tag-ratinho"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/139902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=139902"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/139902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/139905"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=139902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=139902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=139902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}