{"id":142181,"date":"2022-10-05T07:30:00","date_gmt":"2022-10-05T10:30:00","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=142181"},"modified":"2022-10-05T00:57:56","modified_gmt":"2022-10-05T03:57:56","slug":"debate-band-adiado-pedido-candidatos-2-turno","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/debate-band-adiado-pedido-candidatos-2-turno\/","title":{"rendered":"Debate na Band \u00e9 adiado a pedido de candidatos do segundo turno; veja nova data"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A <strong><a href=\"https:\/\/instagram.com\/portalpopmais\" target=\"_blank\" rel=\"noopener\">Band<\/a><\/strong> atendeu ao pedido dos candidatos \u00e0 presid\u00eancia da rep\u00fablica neste segundo turno das elei\u00e7\u00f5es deste ano. A data at\u00e9 ent\u00e3o era no pr\u00f3ximo domingo (9), anunciado inclusive pelo jornalista da casa, Douglas Santucci.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, a previs\u00e3o \u00e9 de que o primeiro confronto entre <a href=\"https:\/\/portalpopmais.com.br\/en\/lula-nao-ira-debate-sbt\/\" data-type=\"post\" data-id=\"140145\">Luiz In\u00e1cio Lula da Silva (PT)<\/a> e <a href=\"https:\/\/portalpopmais.com.br\/en\/que-decepcao-web-reage-a-video-de-bolsonaro-em-templo-de-maconaria\/\" data-type=\"post\" data-id=\"142103\">Jair Bolsonaro (PL)<\/a> nesta segunda etapa do pleito seja no dia 16 de outubro. Ambas as campanhas alegaram ainda estarem planejando suas estrat\u00e9gias at\u00e9 o dia da vota\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por parte da <a href=\"https:\/\/portalpopmais.com.br\/en\/pronunciamento-moraes-datena-maior-ibope-band\/\" data-type=\"post\" data-id=\"141953\">Band<\/a> ainda n\u00e3o existe nada oficializado em raz\u00e3o da corrida para realizar os encontros nos estados que ter\u00e3o segundo turno das elei\u00e7\u00f5es. O canal j\u00e1 enviou convites aos jornalistas para acompanhar os debates.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em S\u00e3o Paulo, as aten\u00e7\u00f5es se voltam na disputa pela maior cadeira do Pal\u00e1cio dos Bandeirantes: Tarc\u00edsio de Freitas (Republicanos) e Fernando Haddad (PT). O estado \u00e9 o maior col\u00e9gio eleitoral do pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A temperatura do debate estadual e presidencial dever\u00e3o apontar alguns rumos que os resultados ter\u00e3o no \u00faltimo domingo do m\u00eas, quando mais de 156 milh\u00f5es de brasileiros voltam \u00e0s urnas em todo o Brasil e tamb\u00e9m no exterior.<\/p>","protected":false},"excerpt":{"rendered":"<p>A Band atendeu ao pedido dos candidatos \u00e0 presid\u00eancia da rep\u00fablica neste segundo turno das elei\u00e7\u00f5es deste ano. A data at\u00e9 ent\u00e3o era no pr\u00f3ximo domingo (9), anunciado inclusive pelo jornalista da casa, Douglas Santucci. Agora, a previs\u00e3o \u00e9 de que o primeiro confronto entre Luiz In\u00e1cio Lula da Silva (PT) e Jair Bolsonaro (PL) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":83597,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[181],"tags":[1152,11928],"class_list":["post-142181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-televisao","tag-band","tag-debate-band"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/142181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=142181"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/142181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/83597"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=142181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=142181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=142181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}