{"id":149328,"date":"2022-11-11T10:39:21","date_gmt":"2022-11-11T13:39:21","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=149328"},"modified":"2022-11-11T10:39:25","modified_gmt":"2022-11-11T13:39:25","slug":"maria-lina-xixi-copo-beber-remedio","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/maria-lina-xixi-copo-beber-remedio\/","title":{"rendered":"Gente? Maria Lina, ex de Whindersson, faz xixi em copo e usa para tomar rem\u00e9dio"},"content":{"rendered":"<p>Gente? A influenciadora digital <strong><a href=\"https:\/\/portalpopmais.com.br\/en\/maria-lina-whindersson-terminaram\/\" data-type=\"post\" data-id=\"89732\">Maria Lina<\/a><\/strong>, ex de Whindersson Nunes, deixou seus seguidores perplexos ao contar uma situa\u00e7\u00e3o que viveu ap\u00f3s fazer uma lipoaspira\u00e7\u00e3o.<\/p>\n\n\n\n<p>Acontece que, durante o p\u00f3s-operat\u00f3rio, Maria n\u00e3o conseguia sair da cama e precisou urinar dentro de um copo. Por\u00e9m, ela acabou usando o mesmo recipiente para tomar um <a href=\"http:\/\/instagram.com\/portalpopmais\" target=\"_blank\" rel=\"noopener\">rem\u00e9dio<\/a>. <\/p>\n\n\n\n<p><em>&#8220;Vou me expor ao rid\u00edculo, mas preciso contar essa situa\u00e7\u00e3o. Quando fiz a lipo, eu estava com dificuldade de sair da cama e fiz xixi em um copo de pl\u00e1stico de festa&#8221;,<\/em> come\u00e7ou ela.<\/p>\n\n\n\n<p>O recipiente havia sido lavado, mas ainda assim a morena ficou em choque ao relembrar. <em>&#8220;A\u00ed lavamos o copo e deixamos no canto da penteadeira do quarto. Depois de um dia, minha m\u00e3e me deu \u00e1gua e rem\u00e9dio pra tomar nesse copo\u2026 tomei e fiquei &#8216;Meu Deus'&#8221;<\/em>, finalizou ela.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"470\" height=\"694\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2022\/11\/ex-de-whindersson-470x694.png\" alt=\"ex de whindersson\" class=\"wp-image-149330\" title=\"\"><figcaption class=\"wp-element-caption\">Foto: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Gente? A influenciadora digital Maria Lina, ex de Whindersson Nunes, deixou seus seguidores perplexos ao contar uma situa\u00e7\u00e3o que viveu ap\u00f3s fazer uma lipoaspira\u00e7\u00e3o. Acontece que, durante o p\u00f3s-operat\u00f3rio, Maria n\u00e3o conseguia sair da cama e precisou urinar dentro de um copo. Por\u00e9m, ela acabou usando o mesmo recipiente para tomar um rem\u00e9dio. &#8220;Vou me [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":144863,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[8164,2276],"class_list":["post-149328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-maria-lina","tag-whindersson-nunes"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/149328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=149328"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/149328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/144863"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=149328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=149328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=149328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}