{"id":16431,"date":"2019-02-06T12:06:31","date_gmt":"2019-02-06T14:06:31","guid":{"rendered":"http:\/\/popmais.com.br\/?p=16431"},"modified":"2019-02-06T12:06:31","modified_gmt":"2019-02-06T14:06:31","slug":"ariana-grande-revela-nome-do-proximo-single-do-album-thank-u-next","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/ariana-grande-revela-nome-do-proximo-single-do-album-thank-u-next\/","title":{"rendered":"Ariana Grande revela nome de seu pr\u00f3ximo single"},"content":{"rendered":"<p>&#8220;7 rings&#8221; segue liderando as principais paradas do mundo, mas Ariana Grande j\u00e1 pensa na sua sucessora.<\/p>\n<p>Em resposta \u00e0 um f\u00e3 no Twitter, a cantora revelou o nome do seu pr\u00f3ximo single. A escolhida foi a track 12 do \u00e1lbum, intitulada &#8220;break up with your girlfriend, i\u2019m bored&#8221;. A data de lan\u00e7amento? Ainda n\u00e3o se sabe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16433\" src=\"http:\/\/popmais.com.br\/wp-content\/uploads\/2019\/02\/50244772_542635589577752_9100861325494072320_n.jpg\" alt=\"\" width=\"1080\" height=\"1080\" title=\"\"><\/p>\n<p>Nesta sexta-feira(08), Ari libera o aguardado \u00e1lbum &#8220;thank u, next&#8221;, que j\u00e1 coleciona dois #1 na Billboard Hot 100.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"1EscBYxLl3\"><p><a href=\"https:\/\/popmais.com.br\/omg-ariana-grande-revela-tracklist-e-data-de-lancamento-de-seu-novo-album\/\" target=\"_blank\" rel=\"noopener\">OMG! Ariana Grande revela tracklist e data de lan\u00e7amento de seu novo \u00e1lbum<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" title=\"&#8220;OMG! Ariana Grande revela tracklist e data de lan\u00e7amento de seu novo \u00e1lbum&#8221; &#8212; POP Mais\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/popmais.com.br\/omg-ariana-grande-revela-tracklist-e-data-de-lancamento-de-seu-novo-album\/embed\/#?secret=1EscBYxLl3\" data-secret=\"1EscBYxLl3\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8220;7 rings&#8221; segue liderando as principais paradas do mundo, mas Ariana Grande j\u00e1 pensa na sua sucessora. Em resposta \u00e0 um f\u00e3 no Twitter, a cantora revelou o nome do seu pr\u00f3ximo single. A escolhida foi a track 12 do \u00e1lbum, intitulada &#8220;break up with your girlfriend, i\u2019m bored&#8221;. A data de lan\u00e7amento? Ainda n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[21],"class_list":["post-16431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-ariana-grande"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/16431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=16431"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/16431\/revisions"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=16431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=16431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=16431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}