{"id":184312,"date":"2023-06-30T14:28:31","date_gmt":"2023-06-30T17:28:31","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=184312"},"modified":"2023-06-30T14:44:47","modified_gmt":"2023-06-30T17:44:47","slug":"apos-polemicas-com-patricia-poeta-manoel-soares-deixa-a-tv-globo","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/apos-polemicas-com-patricia-poeta-manoel-soares-deixa-a-tv-globo\/","title":{"rendered":"Ap\u00f3s pol\u00eamicas com Patr\u00edcia Poeta, Globo demite Manoel Soares"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/portalpopmais.com.br\/en\/apos-polemicas-com-patricia-poeta-manoel-soares-deixa-a-tv-globo\/\" data-type=\"post\" data-id=\"184312\">Manoel Soares<\/a><\/strong> deixou a <a href=\"http:\/\/Redeglobo.globo.com\" target=\"_blank\" rel=\"noopener\">TV Globo<\/a>, nesta sexta-feira (30). A informa\u00e7\u00e3o foi confirmada pela emissora em nota enviada \u00e0 imprensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em comunicado super objetivo, o canal informou sobre as mudan\u00e7as na programa\u00e7\u00e3o a partir da pr\u00f3xima segunda-feira. Veja na \u00edntegra:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;O apresentador Manoel Soares, dos programas &#8216;Encontro com Patr\u00edcia Poeta&#8217; da TV Globo e do &#8216;Papo de Segunda&#8217; do GNT, deixou a Globo nesta sexta-feira. Como a apresentadora Patr\u00edcia Poeta entra de f\u00e9rias na segunda-feira, at\u00e9 a sua volta o programa das manh\u00e3s da TV Globo ser\u00e1 comandado por Tati Machado e Valeria Almeida, que j\u00e1 fazem parte do time da atra\u00e7\u00e3o. No dia 17 de julho, Patr\u00edcia Poeta retomar\u00e1 a apresenta\u00e7\u00e3o do &#8216;Encontro&#8217;, que, depois de um ano no ar com o formato atual, trar\u00e1 novidades. J\u00e1 o programa &#8216;Papo de Segunda&#8217; do GNT passar\u00e1 a ser liderado, a partir da semana que vem, por Jo\u00e3o Vicente de Castro&#8221;.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pol\u00eamicas com Patr\u00edcia Poeta<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que estreou no &#8220;Encontro&#8221; com Patr\u00edcia Poeta, Manoel Soares se viu silenciado diversas vezes pela apresentadora titular. O clima tenso no ar e nos bastidores da atra\u00e7\u00e3o levantaram diversas discuss\u00f5es entre os internautas. Veja tudo <a href=\"https:\/\/portalpopmais.com.br\/en\/video-ao-vivo-patricia-poeta-corta-manoel-soares-e-e-detonada-na-web\/\" data-type=\"post\" data-id=\"174662\">aqui<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Manoel Soares deixou a TV Globo, nesta sexta-feira (30). A informa\u00e7\u00e3o foi confirmada pela emissora em nota enviada \u00e0 imprensa. Em comunicado super objetivo, o canal informou sobre as mudan\u00e7as na programa\u00e7\u00e3o a partir da pr\u00f3xima segunda-feira. Veja na \u00edntegra: &#8220;O apresentador Manoel Soares, dos programas &#8216;Encontro com Patr\u00edcia Poeta&#8217; da TV Globo e do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":184318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[181],"tags":[10802],"class_list":["post-184312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-televisao","tag-manoel-soares"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/184312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=184312"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/184312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/184318"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=184312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=184312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=184312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}