{"id":188688,"date":"2023-08-23T10:40:12","date_gmt":"2023-08-23T13:40:12","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=188688"},"modified":"2023-08-23T10:40:21","modified_gmt":"2023-08-23T13:40:21","slug":"arquetipo-rafa-lanca-me-leve-segundo-single-do-album-de-estreia","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/arquetipo-rafa-lanca-me-leve-segundo-single-do-album-de-estreia\/","title":{"rendered":"Arqu\u00e9tipo Rafa lan\u00e7a \u201cMe Leve\u201d, segundo single do \u00e1lbum de estreia"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Apresentando mais uma faceta do seu \u00e1lbum de estreia, o cantor, compositor e multi-instrumentista <strong>Arqu\u00e9tipo Rafa<\/strong> lan\u00e7a \u201c<a href=\"https:\/\/www.youtube.com\/watch?v=5KwQIgeGJ-s\" target=\"_blank\" rel=\"noopener\">Me Leve<\/a>\u201d, trazendo uma tem\u00e1tica mais densa, embora tratada com suavidade. A faixa vem acompanhada por um filme dirigido por Patr\u00edcia Ara\u00fajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se contrapondo esteticamente ao primeiro single rec\u00e9m-lan\u00e7ado, &#8220;Feito Ladeira&#8221;, em parceria com Alessandra Le\u00e3o, Arqu\u00e9tipo Rafa agora nos apresenta seu lado mais sens\u00edvel no novo disco. O luto, que geralmente pode ser tratado como um tabu, \u00e9 representado nessa can\u00e7\u00e3o acompanhado por sentimentos de carinho e esperan\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u201cMe leve\u201d tenta falar sobre uma sensa\u00e7\u00e3o que est\u00e1 entre n\u00f3s o tempo todo. Muitas vezes, tememos expor nossa vulnerabilidade e n\u00e3o conversamos sobre a perda de algu\u00e9m que n\u00e3o vai mais voltar. O luto est\u00e1 presente no nosso cotidiano todos os dias, principalmente depois de um per\u00edodo hist\u00f3rico em que tantas pessoas se foram&#8221;, contou Rafa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para acompanhar esse tom melanc\u00f3lico, a faixa, que tem a produ\u00e7\u00e3o musical assinada por Arthur Dossa, conta com a participa\u00e7\u00e3o especial do pianista V\u00edtor Ara\u00fajo, al\u00e9m dos arranjos de Mateus Alves (Bacurau), executados por Paula Bujes e Pedro Huff e coro de Bruna Alimonda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;A m\u00fasica oscila entre a tristeza e a alegria, e o arranjo acompanha as nuances da letra de uma forma muito sens\u00edvel. Trouxemos uma imagem do Brasil da d\u00e9cada de 60\/70, que ajudou a dar essa sensa\u00e7\u00e3o de nostalgia que a letra tem. Uma letra que fala de mem\u00f3rias e lembran\u00e7as, somadas a uma sonoridade caracter\u00edstica de um outro per\u00edodo. Tudo isso torna a faixa muito sensorial\u2026e sempre que ou\u00e7o, me emociono&#8221;, completou.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Arqu\u00e9tipo Rafa - Me Leve\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/5KwQIgeGJ-s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Apresentando mais uma faceta do seu \u00e1lbum de estreia, o cantor, compositor e multi-instrumentista Arqu\u00e9tipo Rafa lan\u00e7a \u201cMe Leve\u201d, trazendo uma tem\u00e1tica mais densa, embora tratada com suavidade. A faixa vem acompanhada por um filme dirigido por Patr\u00edcia Ara\u00fajo. Se contrapondo esteticamente ao primeiro single rec\u00e9m-lan\u00e7ado, &#8220;Feito Ladeira&#8221;, em parceria com Alessandra Le\u00e3o, Arqu\u00e9tipo Rafa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":188691,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[15520],"class_list":["post-188688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-arquetipo-rafa"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/188688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=188688"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/188688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/188691"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=188688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=188688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=188688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}