{"id":200221,"date":"2024-01-03T09:09:35","date_gmt":"2024-01-03T12:09:35","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=200221"},"modified":"2024-01-03T09:12:47","modified_gmt":"2024-01-03T12:12:47","slug":"apos-desaparecimento-sthefanny-carvalho-e-mc-kelvin-sao-encontrados-no-chile","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/apos-desaparecimento-sthefanny-carvalho-e-mc-kelvin-sao-encontrados-no-chile\/","title":{"rendered":"Ap\u00f3s desaparecimento, Sthefanny Carvalho e MC Kelvin s\u00e3o encontrados no Chile"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A equipe da tiktoker <strong><a href=\"http:\/\/portalpopmais.com.br\/en\/\">Sthefanny Carvalho<\/a><\/strong> informou, nesta ter\u00e7a (02\/11), que a jovem e o namorado dela, <strong><a href=\"http:\/\/instagram.com\/popmaisfm\" target=\"_blank\" rel=\"noopener\">MC Kelvin<\/a><\/strong>, que estavam desaparecidos desde o dia 31 de dezembro do ano passado, j\u00e1 foram encontrados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ontem, a fam\u00edlia publicou um comunicado nas redes sociais da jovem, onde dizia que o casal de influenciadores havia viajado para o Chile, mas pedido o contato com familiares e amigos logo ap\u00f3s uma publica\u00e7\u00e3o misteriosa dentro de um carro.  <\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">Leia mais<\/h2>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 aligncenter wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/renata-vasconcellos-pode-deixar-a-bancada-do-jornal-nacional-em-2027-diz-colunista\/\" aria-label=\"Renata Vasconcellos pode deixar a bancada do Jornal Nacional em 2027, diz colunista\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2023\/01\/Globo-SP-FHD-20230112-205556-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2023\/01\/Globo-SP-FHD-20230112-205556-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2023\/01\/Globo-SP-FHD-20230112-205556-1170x694.png 1170w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/renata-vasconcellos-pode-deixar-a-bancada-do-jornal-nacional-em-2027-diz-colunista\/\">Renata Vasconcellos pode deixar a bancada do Jornal Nacional em 2027, diz colunista<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/virginia-compra-apartamento-milionario-em-predio-de-neymar\/\" aria-label=\"Virginia compra apartamento milion\u00e1rio em pr\u00e9dio de Neymar\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"mp investiga blaze contratos neymar virginia\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-1170x694.png 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-18x12.png 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/virginia-compra-apartamento-milionario-em-predio-de-neymar\/\">Virginia compra apartamento milion\u00e1rio em pr\u00e9dio de Neymar<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/cartolouco-se-pronuncia-contesta-acusacoes-de-agressao-e-rebate-ex-veja-o-video\/\" aria-label=\"Cartolouco se pronuncia, contesta acusa\u00e7\u00f5es de agress\u00e3o e rebate ex; veja o v\u00eddeo\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2020\/12\/Design-sem-nome-23-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Lucas Cartolouco para Rede Record\" style=\"\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/cartolouco-se-pronuncia-contesta-acusacoes-de-agressao-e-rebate-ex-veja-o-video\/\">Cartolouco se pronuncia, contesta acusa\u00e7\u00f5es de agress\u00e3o e rebate ex; veja o v\u00eddeo<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/homem-processa-virginia-e-outros-influencers-apos-perder-r-100-mil-em-bets\/\" aria-label=\"Homem processa Virginia e outros influenciadores ap\u00f3s perder R$ 100 mil em bets\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/02\/virginia-passa-mal-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Virginia Fonseca - Foto: Reprodu\u00e7\u00e3o Instagram\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/02\/virginia-passa-mal-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/02\/virginia-passa-mal-1170x694.png 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/02\/virginia-passa-mal-18x10.png 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/homem-processa-virginia-e-outros-influencers-apos-perder-r-100-mil-em-bets\/\">Homem processa Virginia e outros influenciadores ap\u00f3s perder R$ 100 mil em bets<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/casamento-de-ryan-gosling-e-eva-mendes-enfrenta-momento-delicado-diz-site\/\" aria-label=\"Casamento de Ryan Gosling e Eva Mendes enfrenta momento delicado, diz site\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/Ryan-Gosling-e-Eva-Mendes-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Ryan Gosling e Eva Mendes\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/Ryan-Gosling-e-Eva-Mendes-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/Ryan-Gosling-e-Eva-Mendes-18x10.png 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/casamento-de-ryan-gosling-e-eva-mendes-enfrenta-momento-delicado-diz-site\/\">Casamento de Ryan Gosling e Eva Mendes enfrenta momento delicado, diz site<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/ariana-grande-reacende-rumores-de-volta-com-ex-namorado\/\" aria-label=\"Ariana Grande reacende rumores de volta com ex-namorado\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2024\/01\/ariana-grande-768x456.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"ariana grande\" style=\"\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/ariana-grande-reacende-rumores-de-volta-com-ex-namorado\/\">Ariana Grande reacende rumores de volta com ex-namorado<\/a><\/li>\n<\/ul><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNa noite de 31 de dezembro de 2023, enquanto explorava o Chile durante uma viagem, a influenciadora Sthefanny Carvalho compartilhou em seus stories um v\u00eddeo mostrando o interior de um carro enquanto percorria uma estrada escura, at\u00e9 onde sabemos, na companhia de seu namorado, o MC Kelvin. Contudo, ap\u00f3s essa postagem, familiares e amigos n\u00e3o conseguiram estabelecer contato com o casal, gerando preocupa\u00e7\u00e3o imediatamente, sobretudo pelo fato de estarem em territ\u00f3rio estrangeiro. At\u00e9 o presente momento (02 de janeiro de 2023), n\u00e3o temos mais nenhuma informa\u00e7\u00e3o sobre o paradeiro de ambos\u201d, dizia o comunicado publicado<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">Leia mais<\/h2>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 aligncenter wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/do-interior-do-para-ao-rio-de-janeiro-cris-terra-transforma-sucesso-nas-redes-em-novo-capitulo-na-carreira\/\" aria-label=\"Do interior do Par\u00e1 ao Rio de Janeiro: Cris Terra transforma sucesso nas redes em novo cap\u00edtulo na carreira\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/IMG-20260714-WA0016-768x456.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"IMG 20260714 WA0016\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/IMG-20260714-WA0016-768x456.jpg 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/IMG-20260714-WA0016-1170x694.jpg 1170w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/do-interior-do-para-ao-rio-de-janeiro-cris-terra-transforma-sucesso-nas-redes-em-novo-capitulo-na-carreira\/\">Do interior do Par\u00e1 ao Rio de Janeiro: Cris Terra transforma sucesso nas redes em novo cap\u00edtulo na carreira<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/sunk-cost-marca-nova-fase-artistica-de-rxrxbbit-com-critica-social-e-experimentacao-sonora\/\" aria-label=\"&#8220;SUNK COST&#8221; marca nova fase art\u00edstica de RXRXBBIT com cr\u00edtica social e experimenta\u00e7\u00e3o sonora\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/prod_track-files_1496974_extra_pictures_RXRXBBIT-e1784039130618-768x456.jpeg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"prod track files 1496974 extra pictures RXRXBBIT\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/prod_track-files_1496974_extra_pictures_RXRXBBIT-e1784039130618-768x456.jpeg 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/prod_track-files_1496974_extra_pictures_RXRXBBIT-e1784039130618-1170x694.jpeg 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/prod_track-files_1496974_extra_pictures_RXRXBBIT-e1784039130618-18x12.jpeg 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/sunk-cost-marca-nova-fase-artistica-de-rxrxbbit-com-critica-social-e-experimentacao-sonora\/\">&#8220;SUNK COST&#8221; marca nova fase art\u00edstica de RXRXBBIT com cr\u00edtica social e experimenta\u00e7\u00e3o sonora<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/renata-vasconcellos-pode-deixar-a-bancada-do-jornal-nacional-em-2027-diz-colunista\/\" aria-label=\"Renata Vasconcellos pode deixar a bancada do Jornal Nacional em 2027, diz colunista\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2023\/01\/Globo-SP-FHD-20230112-205556-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2023\/01\/Globo-SP-FHD-20230112-205556-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2023\/01\/Globo-SP-FHD-20230112-205556-1170x694.png 1170w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/renata-vasconcellos-pode-deixar-a-bancada-do-jornal-nacional-em-2027-diz-colunista\/\">Renata Vasconcellos pode deixar a bancada do Jornal Nacional em 2027, diz colunista<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/virginia-compra-apartamento-milionario-em-predio-de-neymar\/\" aria-label=\"Virginia compra apartamento milion\u00e1rio em pr\u00e9dio de Neymar\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"mp investiga blaze contratos neymar virginia\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-1170x694.png 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/06\/mp-investiga-blaze-contratos-neymar-virginia-18x12.png 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/virginia-compra-apartamento-milionario-em-predio-de-neymar\/\">Virginia compra apartamento milion\u00e1rio em pr\u00e9dio de Neymar<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/fisiculturista-e-influenciador-baiano-morre-aos-37-anos-apos-passar-mal-em-casa\/\" aria-label=\"Fisiculturista e influenciador baiano morre aos 37 anos ap\u00f3s passar mal em casa\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/morre-fisiculturista-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"morre fisiculturista\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/morre-fisiculturista-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/07\/morre-fisiculturista-18x12.png 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/fisiculturista-e-influenciador-baiano-morre-aos-37-anos-apos-passar-mal-em-casa\/\">Fisiculturista e influenciador baiano morre aos 37 anos ap\u00f3s passar mal em casa<\/a><\/li>\n<\/ul><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNa noite de 31 de dezembro de 2023, enquanto explorava o Chile durante uma viagem, a influenciadora Sthefanny Carvalho compartilhou em seus stories um v\u00eddeo mostrando o interior de um carro enquanto percorria uma estrada escura, at\u00e9 onde sabemos, na companhia de seu namorado, o MC Kelvin. Contudo, ap\u00f3s essa postagem, familiares e amigos n\u00e3o conseguiram estabelecer contato com o casal, gerando preocupa\u00e7\u00e3o imediatamente, sobretudo pelo fato de estarem em territ\u00f3rio estrangeiro. At\u00e9 o presente momento (02 de janeiro de 2023), n\u00e3o temos mais nenhuma informa\u00e7\u00e3o sobre o paradeiro de ambos\u201d, dizia o comunicado publicado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Casal localizado<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda na noite de ter\u00e7a-feira (2), ap\u00f3s a repercuss\u00e3o do poss\u00edvel desaparecimento, Ester Santos, m\u00e3e da influenciadora, voltou \u00e0s redes sociais para informar que o casal havia sido localizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Vim aqui para avisar para voc\u00eas que a Stephanie quer entrar em contato comigo, gra\u00e7as a Deus. Eu j\u00e1 entrei em contato com a m\u00e3e dele, com os familiares dele tamb\u00e9m. Eles est\u00e3o bem, e com sa\u00fade, isso que importa&#8221;, iniciou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ester ainda relatou que n\u00e3o sabe o motivo do desaparecimento do casal. &#8220;Eu n\u00e3o sei ainda o que realmente aconteceu, mas quando eles retornarem aqui, quando eles chegarem aqui ao Brasil, eles v\u00e3o contar, eles v\u00e3o conversar, falar para a gente o que aconteceu&#8221;, revelou.<\/p>","protected":false},"excerpt":{"rendered":"<p>A equipe da tiktoker Sthefanny Carvalho informou, nesta ter\u00e7a (02\/11), que a jovem e o namorado dela, MC Kelvin, que estavam desaparecidos desde o dia 31 de dezembro do ano passado, j\u00e1 foram encontrados. Ontem, a fam\u00edlia publicou um comunicado nas redes sociais da jovem, onde dizia que o casal de influenciadores havia viajado para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":200222,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[15100],"class_list":["post-200221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-sthefanny-carvalho"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/200221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=200221"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/200221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/200222"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=200221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=200221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=200221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}