{"id":200301,"date":"2024-01-04T09:14:31","date_gmt":"2024-01-04T12:14:31","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=200301"},"modified":"2024-01-04T09:14:43","modified_gmt":"2024-01-04T12:14:43","slug":"escandalo-bill-clinton-e-principe-andrew-aparecem-na-lista-de-pessoas-ligadas-a-jeffrey-epstein","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/escandalo-bill-clinton-e-principe-andrew-aparecem-na-lista-de-pessoas-ligadas-a-jeffrey-epstein\/","title":{"rendered":"ESC\u00c2NDALO! Bill Clinton e Pr\u00edncipe Andrew aparecem na lista de pessoas ligadas a Jeffrey Epstein"},"content":{"rendered":"<p><strong><a href=\"https:\/\/portalpopmais.com.br\/en\/dwayne-hickman-morre-87-anos\/\" data-type=\"post\" data-id=\"101391\">Bill Clinton<\/a><\/strong>, ex-presidente dos Estados Unidos,  o pr\u00edncipe Andrew do Reino Unido, e outros 185 nomes, est\u00e3o entre as figuras ligadas a Jeffrey Epstein, o bilion\u00e1rio norte-americano respons\u00e1vel por um esquema de tr\u00e1fico sexual. De acordo com a CNN, a informa\u00e7\u00e3o foi divulgada na quarta-feira (3) ap\u00f3s a Justi\u00e7a dos Estados Unidos tornar p\u00fablico uma s\u00e9rie de documentos relacionados ao processo do criminoso.<\/p>\n\n\n\n<p>Epstein confessou em 2008 sua culpa por pedir prostitui\u00e7\u00e3o a uma menor de idade. J\u00e1 em 2019, aos 66 anos, foi encontrado morto em uma cela enquanto aguardava julgamento por acusa\u00e7\u00f5es de tr\u00e1fico sexual. Na \u00e9poca, sua morte foi considerada como suic\u00eddio.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">Leia mais<\/h2>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 aligncenter wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/familia-faz-novas-acusacoes-contra-michael-jackson-e-relata-decadas-de-abusos\/\" aria-label=\"Fam\u00edlia faz novas acusa\u00e7\u00f5es contra Michael Jackson e relata d\u00e9cadas de abusos\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/03\/Michael-Jackson-POP-Mais-768x456.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Michael Jackson - POP Mais\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/03\/Michael-Jackson-POP-Mais-768x456.jpg 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/03\/Michael-Jackson-POP-Mais-1170x694.jpg 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/03\/Michael-Jackson-POP-Mais-18x10.jpg 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/familia-faz-novas-acusacoes-contra-michael-jackson-e-relata-decadas-de-abusos\/\">Fam\u00edlia faz novas acusa\u00e7\u00f5es contra Michael Jackson e relata d\u00e9cadas de abusos<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/ex-de-shakira-pique-aponta-brasil-como-decepcao-da-copa-do-mundo-e-revolta-brasileiros\/\" aria-label=\"Ex de Shakira, Piqu\u00e9 aponta Brasil como decep\u00e7\u00e3o da Copa do Mundo e revolta brasileiros\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/pique-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"piqu\u00e9\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/pique-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/pique-18x12.png 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/ex-de-shakira-pique-aponta-brasil-como-decepcao-da-copa-do-mundo-e-revolta-brasileiros\/\">Ex de Shakira, Piqu\u00e9 aponta Brasil como decep\u00e7\u00e3o da Copa do Mundo e revolta brasileiros<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/kevin-riley-aposta-em-pop-cinematografico-no-single-chaos\/\" aria-label=\"Kevin Riley aposta em pop cinematogr\u00e1fico no single \u201cCHAOS\u201d\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1667800_extra_pictures_Kevin-Riley-1-768x456.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"prod track files 1667800 extra pictures Kevin Riley\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1667800_extra_pictures_Kevin-Riley-1-768x456.png 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1667800_extra_pictures_Kevin-Riley-1-1170x694.png 1170w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/kevin-riley-aposta-em-pop-cinematografico-no-single-chaos\/\">Kevin Riley aposta em pop cinematogr\u00e1fico no single \u201cCHAOS\u201d<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/banda-modiste-estreia-no-synth-pop-com-single-breaking-my-own-heart\/\" aria-label=\"Banda MODISTE estreia no synth-pop com single \u201cBreaking My Own Heart\u201d\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1674876_extra_pictures_MODISTE-768x456.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"prod track files 1674876 extra pictures MODISTE\" style=\"\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/banda-modiste-estreia-no-synth-pop-com-single-breaking-my-own-heart\/\">Banda MODISTE estreia no synth-pop com single \u201cBreaking My Own Heart\u201d<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/julio-meloni-relanca-album-herdeiro-da-lua-em-edicao-deluxe-com-faixas-ineditas-e-nova-identidade-visual\/\" aria-label=\"Julio Meloni relan\u00e7a \u00e1lbum \u201cHerdeiro da Lua\u201d em edi\u00e7\u00e3o deluxe com faixas in\u00e9ditas e nova identidade visual\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1499642_extra_pictures_Julio-Meloni-768x456.jpeg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"prod track files 1499642 extra pictures Julio Meloni\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1499642_extra_pictures_Julio-Meloni-768x456.jpeg 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1499642_extra_pictures_Julio-Meloni-1170x694.jpeg 1170w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/julio-meloni-relanca-album-herdeiro-da-lua-em-edicao-deluxe-com-faixas-ineditas-e-nova-identidade-visual\/\">Julio Meloni relan\u00e7a \u00e1lbum \u201cHerdeiro da Lua\u201d em edi\u00e7\u00e3o deluxe com faixas in\u00e9ditas e nova identidade visual<\/a><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/portalpopmais.com.br\/en\/ator-matthew-jablonski-anuncia-nova-fase-na-musica-com-projeto-autoral-futurista\/\" aria-label=\"Ator Matthew Jablonski anuncia nova fase na m\u00fasica com projeto autoral futurista\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"456\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1701921_extra_pictures_Matthew-Jablonski-768x456.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"prod track files 1701921 extra pictures Matthew Jablonski\" style=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1701921_extra_pictures_Matthew-Jablonski-768x456.jpg 768w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1701921_extra_pictures_Matthew-Jablonski-1170x694.jpg 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2026\/05\/prod_track-files_1701921_extra_pictures_Matthew-Jablonski-18x12.jpg 18w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\"><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/portalpopmais.com.br\/en\/ator-matthew-jablonski-anuncia-nova-fase-na-musica-com-projeto-autoral-futurista\/\">Ator Matthew Jablonski anuncia nova fase na m\u00fasica com projeto autoral futurista<\/a><\/li>\n<\/ul><\/div><\/div>\n\n\n\n<p>Dezenas de mulheres o acusaram de for\u00e7\u00e1-las a prestar servi\u00e7os sexuais em sua ilha <a href=\"http:\/\/twitter.com\/popmaisfm\" target=\"_blank\" rel=\"noopener\">particular<\/a> no Caribe e em suas propriedades em Nova York, Fl\u00f3rida e Novo M\u00e9xico. Virginia Giuffre, uma das principais acusadoras de Epstein, afirmou ter tido rela\u00e7\u00f5es sexuais com v\u00e1rios pol\u00edticos e l\u00edderes financeiros proeminentes, incluindo George Mitchell, ex-senador dos EUA, e Bill Richardson, ex-governador do Estado do Novo M\u00e9xico.<\/p>\n\n\n\n<p>Nomes de mais de 150 pessoas mencionadas no processo movido por Virginia foram mantidos sob sigilo at\u00e9 o m\u00eas passado, quando a ju\u00edza federal que supervisiona o caso, Loretta Preska, decidiu que n\u00e3o havia justificativa legal para mant\u00ea-los privados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Os documentos<\/h2>\n\n\n\n<p>Loretta Preska observou que a maioria dos nomes j\u00e1 havia sido divulgada publicamente em outros processos ou em reportagens.<\/p>\n\n\n\n<p>A maioria dos documentos tornados p\u00fablicos nesta quarta-feira n\u00e3o inclui epis\u00f3dios espec\u00edficos de irregularidades cometidas por outros homens, al\u00e9m de Epstein.<\/p>\n\n\n\n<p>Entre os documentos revelados na quarta-feira estava um extenso depoimento de maio de 2016 de Johanna Sjoberg, uma das supostas v\u00edtimas de Epstein, que disse ter convivido com o financista de 2001 a 2006. Foi perguntado a ela se Jeffrey alguma vez falou com ela sobre Clinton durante esse per\u00edodo.<\/p>\n\n\n\n<p>\u2014 Ele disse uma vez que Clinton gosta delas jovens, referindo-se a meninas \u2014 testemunhou Sjoberg. Ela tamb\u00e9m disse que, enquanto voava com Epstein em um de seus avi\u00f5es, eles fizeram uma parada n\u00e3o planejada em Atlantic City, N.J.<\/p>\n\n\n\n<p>\u2014 Jeffrey disse: &#8220;\u00f3timo, vamos ligar para o Trump&#8221; \u2014 testemunhou Sjoberg, acrescentando que Epstein sugeriu que eles visitassem o cassino de Donald Trump.<\/p>\n\n\n\n<p>Quanto ao pr\u00edncipe Andrew, o segundo filho da Rainha Elizabeth II, Sjoberg testemunhou que, quando foi apresentada a ele pela primeira vez, ele \u201ccolocou a m\u00e3o em meu peito\u201d. Em 2019, Andrew anunciou sua retirada da vida p\u00fablica, ap\u00f3s esc\u00e2ndalo gerado por sua amizade com o empres\u00e1rio americano.<\/p>\n\n\n\n<p>A maioria das pessoas famosas ligadas ao Epstein disse que n\u00e3o tinha conhecimento de seu comportamento abusivo com meninas adolescentes ou mulheres jovens.<\/p>\n\n\n\n<p>Clinton emitiu uma declara\u00e7\u00e3o em 2019 dizendo que n\u00e3o sabia nada sobre os \u201ccrimes terr\u00edveis\u201d de Epstein. O ex-presidente nunca foi acusado de qualquer irregularidade relacionada ao Jeffrey; e ele n\u00e3o se op\u00f4s \u00e0 divulga\u00e7\u00e3o dos documentos que o mencionam, disse um porta-voz na noite de quarta-feira. J\u00e1 Trump disse que teve uma \u201cdesaven\u00e7a\u201d com Epstein anos atr\u00e1s e \u201cn\u00e3o era um f\u00e3\u201d.<\/p>\n\n\n\n<p>No total, a ju\u00edza Preska ordenou a revela\u00e7\u00e3o de mais de 200 documentos, sendo que o restante dever\u00e1 ser divulgado nos pr\u00f3ximos dias, ap\u00f3s serem revisados pelos advogados envolvidos no lit\u00edgio.<\/p>\n\n\n\n<p>Os materiais compreendem, na maioria, mo\u00e7\u00f5es legais e trechos de depoimentos dados por acusadores que descrevem em detalhes como Epstein abusou sexualmente deles, inclusive for\u00e7ando-os a masturb\u00e1-lo durante massagens.<\/p>\n\n\n\n<p>A ju\u00edza Preska disse em seu despacho que os documentos, em sua maioria, n\u00e3o inclu\u00edam material obsceno sobre outras pessoas al\u00e9m do criminoso.<\/p>\n\n\n\n<p>Ao explicar sua decis\u00e3o de abrir os documentos, a ju\u00edza Preska observou v\u00e1rios casos em que um determinado \u201cDoe\u201d n\u00e3o havia levantado obje\u00e7\u00e3o \u00e0 divulga\u00e7\u00e3o de seu nome. Mas em outros casos, ela ordenou que a confidencialidade fosse mantida.<\/p>\n\n\n\n<p>&#8220;O &#8216;Doe 16&#8217; \u00e9 uma suposta v\u00edtima menor de abuso sexual que n\u00e3o se manifestou publicamente e que manteve sua privacidade\u201d, escreveu a ju\u00edza Preska em um caso. \u201cDessa forma, o interesse p\u00fablico n\u00e3o supera o interesse da privacidade\u201d, acrescentou.<\/p>\n\n\n\n<p>Os documentos foram originalmente apresentados como parte de um processo de difama\u00e7\u00e3o movido em 2015 por Virginia Giuffre contra a socialite brit\u00e2nica Ghislaine Maxwell, ex-namorada de Epstein, condenada em 2021 por ser c\u00famplice dele em sua opera\u00e7\u00e3o de tr\u00e1fico sexual. Ghislaine est\u00e1 cumprindo uma senten\u00e7a de 20 anos de pris\u00e3o por traficar jovens v\u00edtimas de abuso sexual para Jeffrey.<\/p>\n\n\n\n<p>Em 2022, Giuffre e o pr\u00edncipe Andrew chegaram a um acordo em um processo separado no qual ela alegou que ele havia abusado sexualmente dela quando ela tinha 17 anos.<\/p>\n\n\n\n<p>Sigrid McCawley, advogada de Giuffre, disse que a revela\u00e7\u00e3o dos documentos permitiria ao p\u00fablico saber \u201cmais sobre a escala e o escopo do esquema de Epstein\u201d e como ele conseguiu se safar por tanto tempo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bill Clinton, ex-presidente dos Estados Unidos, o pr\u00edncipe Andrew do Reino Unido, e outros 185 nomes, est\u00e3o entre as figuras ligadas a Jeffrey Epstein, o bilion\u00e1rio norte-americano respons\u00e1vel por um esquema de tr\u00e1fico sexual. De acordo com a CNN, a informa\u00e7\u00e3o foi divulgada na quarta-feira (3) ap\u00f3s a Justi\u00e7a dos Estados Unidos tornar p\u00fablico uma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":200302,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[16063],"class_list":["post-200301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-jeffrey-epstein"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/200301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=200301"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/200301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/200302"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=200301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=200301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=200301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}