{"id":202670,"date":"2024-02-02T09:24:02","date_gmt":"2024-02-02T12:24:02","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=202670"},"modified":"2024-02-02T09:24:20","modified_gmt":"2024-02-02T12:24:20","slug":"lista-descobertas-musicais-da-plataforma-groover-41","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/lista-descobertas-musicais-da-plataforma-groover-41\/","title":{"rendered":"Lista: Descobertas musicais da plataforma Groover"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Selecionei algumas can\u00e7\u00f5es da plataforma\u00a0<a href=\"http:\/\/portalpopmais.com.br\/en\/\">Groover\u00a0<\/a>que voc\u00ea n\u00e3o pode deixar de ouvir, confira abaixo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1 &#8211; ANYMEN &#8211; &#8216;Ghost Story&#8217;: <\/strong>O DJ e m\u00fasico eletr\u00f4nico franc\u00eas Tony Bouilly produz synthwave \/ retrowave electro sob o pseud\u00f4nimo <a href=\"http:\/\/portalpopmais.com.br\/en\/\">ANYMEN<\/a>, uma palavra inventada que simboliza a energia e o impacto que qualquer homem pode trazer para a equa\u00e7\u00e3o global, n\u00e3o importa de onde venha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tony nasceu em Chartres, Fran\u00e7a, em 1987, e come\u00e7ou a ouvir m\u00fasica eletr\u00f4nica ainda adolescente. Ele come\u00e7ou a experimentar sintetizadores de hardware e iniciou faixas depois de se mudar para Paris em 2008. Ele estreou no projeto de m\u00fasica techno Ange Siddhar trabalhando e remixando pioneiros da house music como Paul Johnson, Amy Kirkpatrick, David Duriez, Ron Carroll e muitos mais, em turn\u00ea em clubes e festivais underground ao redor do mundo, apresentando-se em cidades como Chicago, Amsterd\u00e3, Bras\u00edlia, Paris ou Nova York.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ano de destaque de Tony provou ser 2021, quando ele iniciou seu novo projeto ANYMEN do \u00e1lbum &#8216;Voyager&#8217; profundamente influenciado por sua inf\u00e2ncia dos anos 90 ao lado de cantores e instrumentistas talentosos como Man 3 Faces Domine Clemons, Numa, Calvin Davey Jurnalist, Envi Royal, Bassam Bellman e lan\u00e7ando sua performance de v\u00eddeo do \u00e1lbum de est\u00fadio &#8216;Voyager 2021&#8217;.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ghost Story\" width=\"880\" height=\"660\" src=\"https:\/\/www.youtube.com\/embed\/o8o44znHQlA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2 &#8211; ALMAR &#8211; &#8216;\u00c9 Tu&#8217;:<\/strong> Almar, composta por Santino e Bruna Souza. O que come\u00e7ou como um acervo pessoal de dois amigos que escreviam m\u00fasicas para expressarem seus sentimentos, se tornou um grande duo, que j\u00e1 possui mais de cinco EP&#8217;s lan\u00e7ados, al\u00e9m da grava\u00e7\u00e3o &#8220;Almar Ao Vivo&#8221;. O single <a href=\"http:\/\/portalpopmais.com.br\/en\/\">&#8220;\u00c9 Tu&#8221;<\/a> vem viralizando desde o dia dos namorados e os n\u00fameros seguem crescendo em todas as plataformas e redes.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"ALMAR - \u00c9 tu (Clipe Oficial)\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/YLwmdJ6hzUY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3 &#8211; neontown &#8211; &#8216;Come Undone&#8217;:<\/strong> Este \u00e9 o novo single <a href=\"http:\/\/portalpopmais.com.br\/en\/\">Come Undone<\/a> &#8211; da pr\u00f3xima vers\u00e3o deluxe do \u00e1lbum Dancing With Tears In My Eyes. Adoram misturar melodias dos anos 90 com sons mais modernos e criar m\u00fasicas nost\u00e1lgicas mas en\u00e9rgicas!<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Come Undone\" width=\"880\" height=\"660\" src=\"https:\/\/www.youtube.com\/embed\/d1IyYwgPnic?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4 &#8211; Jos\u00e9 Augusto &#8211; &#8216;Jo\u00e3o&#8217;:<\/strong> Fromada no final de 2014, a <a href=\"http:\/\/portalpopmais.com.br\/en\/\">Glasgow9<\/a> tem a proposta de resgatar cl\u00e1ssicos do Rock. Seu nome \u00e9 uma refer\u00eancia ao \u00edndica 9 da escola de coma Glasgow, um estado de obnubila\u00e7\u00e3o. Composta originalmente por 3 m\u00e9dicos e um publicit\u00e1rio, a banda tem a m\u00fasica como uma forma de aliviar a tens\u00e3o da rotina de trabalho. Tendo a PLAY CULTURAL como produtora a banda realizou diversos shows e se tornou a bando oficial do FICC (Festival Internacional da Cerveja e Cultura)<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Jo\u00e3o\" width=\"880\" height=\"660\" src=\"https:\/\/www.youtube.com\/embed\/lhCaGZwcVeA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5 &#8211; Tommi Waring &#8211; &#8216;Don&#8217;t Lose Touch&#8217;:<\/strong> Inspirado no pop\/funk\/soul, este <a href=\"http:\/\/portalpopmais.com.br\/en\/\">disco <\/a>foi criado para trazer vibra\u00e7\u00f5es descoladas e liderar a dan\u00e7a para mais m\u00fasicas novas que est\u00e3o por vir.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Don&#039;t Lose Touch - (Official Video)\" width=\"880\" height=\"660\" src=\"https:\/\/www.youtube.com\/embed\/yfw1uLahfIc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6 &#8211; Magical Island &#8211; &#8216;Friends or Lovers&#8217;:<\/strong> Descubra <a href=\"http:\/\/portalpopmais.com.br\/en\/\">&#8220;Friends or Lovers&#8221;<\/a> de Albert Adelmann e Caro Pieroto (sob o r\u00f3tulo Magic Island), uma jornada musical que confunde os limites entre amizade e romance, desdobrando-se em uma rica tape\u00e7aria de acordes com infus\u00e3o de jazz. Mergulhe em letras sinceras que defendem a conex\u00e3o genu\u00edna, incentivando-nos a abra\u00e7ar o amor em todas as suas formas, sem arrependimentos ou r\u00f3tulos. Junte-se a n\u00f3s em uma dan\u00e7a da vida onde o amor e a amizade se unem em perfeita harmonia.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Friends or Lovers (feat. Diana Purim)\" width=\"880\" height=\"660\" src=\"https:\/\/www.youtube.com\/embed\/5C97BdpEANc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7 &#8211; Tiam Wills &#8211; &#8216;Destiny&#8217;:<\/strong> \u201cDestiny\u201d que tem um duplo significado; expressa o desejo de ir mais longe como casal, de partilhar o seu amor com a sua alma g\u00e9mea, sem se preocupar com o amanh\u00e3, e de construir a sua vida a dois com as mais belas recorda\u00e7\u00f5es. Tamb\u00e9m expressa o destino de cada pessoa, o nosso caminho de vida e o que temos a miss\u00e3o de fazer na terra.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Destiny\" width=\"880\" height=\"660\" src=\"https:\/\/www.youtube.com\/embed\/kvGZXI8iCR4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8 &#8211; AZINHAGA &#8211; &#8216;Corda Bamba&#8217;:<\/strong> Que m\u00fasica <a href=\"http:\/\/portalpopmais.com.br\/en\/\">incr\u00edvel<\/a>! Letra perfeita e arranjos de arrepiar! Parab\u00e9ns pelo vocal t\u00e1 demais!<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Azinhaga - Corda Bamba\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/HQyHn9YeVGQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9 &#8211; Master-D &#8211; &#8216;Preme Joraibani&#8217;:<\/strong> Celebrado como um pioneiro da cena musical #BanglaUrban com mais de 70 milh\u00f5es de visualiza\u00e7\u00f5es org\u00e2nicas, Master-D agora revela um single inovador onde Bangla encontra o Reggaeton. A sua influ\u00eancia n\u00e3o s\u00f3 moldou uma nova era musical na \u00cdndia, mas tamb\u00e9m desempenhou um papel fundamental no lan\u00e7amento bem sucedido do <a href=\"http:\/\/portalpopmais.com.br\/en\/\">Spotify <\/a>no Bangladesh. Como o pioneiro artista urbano bengali que colaborou com a Bohemia na Universal Music India, ele continua a fazer ondas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em seu \u00faltimo lan\u00e7amento, &#8220;Preme Joraibani&#8221;, Master-D une for\u00e7as com a sensa\u00e7\u00e3o canadense do Reggaet\u00f3n, Landy Garcia. Com dois pr\u00eamios canadenses de m\u00fasica latina em seu nome, Landy vem causando um impacto significativo na Am\u00e9rica do Sul, nos EUA e no Canad\u00e1. Juntos, eles misturam a vibra\u00e7\u00e3o r\u00edtmica do Bangla com as batidas energ\u00e9ticas do Reggaeton, impulsionando a m\u00fasica Bangla para o palco global. Este single crossover inovador promete cativar o p\u00fablico do sul da \u00c1sia e do latim com um single crossover inovador.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Master-D x Landy Garcia - Preme Joraibani (Official Music Video) | Bangla Reggaet\u00f3n Song\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/iaw-Khw-hj4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10 &#8211; Carson Ferris &#8211; &#8216;1999&#8217;:<\/strong> Carson Ferris, de 13 anos, j\u00e1 teve uma grande carreira musical e est\u00e1 apenas come\u00e7ando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/portalpopmais.com.br\/en\/\">Carson <\/a>escolheu um instrumento para come\u00e7ar a aprender aos 6 anos e escolheu a guitarra el\u00e9trica. Ele se destacou na performance musical tocando guitarra e cantando em bandas de rock com outros alunos no Rock Lab de Dave Wilbur em Orem, e depois com o aclamado One Voice Children\u2019s Choir. Quando o mundo fechou em 2020, Carson n\u00e3o queria parar de fazer m\u00fasica, ent\u00e3o come\u00e7ou por conta pr\u00f3pria. Ele come\u00e7ou a gravar m\u00fasicas em Los Angeles e lan\u00e7ou Can&#8217;t Be Without You com Trinidad Cardona em outubro de 2021. Tamb\u00e9m em 2021, Carson teve a oportunidade de ter um v\u00eddeo dele cantando e dan\u00e7ando One Bad Apple no show de Donny Osmond em Las Vegas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A m\u00fasica de Carson \u00e9 pop com alguma influ\u00eancia do rock. Sua banda favorita de todos os tempos \u00e9 Journey, e sua m\u00fasica \u00e9 influenciada por OneRepublic e artistas solo como Ed Sheran e Jonas Brothers. Carson escreve sua m\u00fasica para ser acess\u00edvel e identific\u00e1vel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de 2020, Carson mudou para o ensino on-line para ter mais tempo para trabalhar em sua m\u00fasica. Ele aproveitou bem esse tempo, j\u00e1 que muitas vezes voc\u00ea pode encontr\u00e1-lo tocando em festivais de m\u00fasica locais como Fork Fest e Buzzards and Bees. Ele tamb\u00e9m se mant\u00e9m ocupado escrevendo m\u00fasicas, trabalhando com o produtor Mykyl e gravando faixas no Provo\u2019s June Audio.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: 1999\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/track\/19cH3G5s6TrM04CWdVhyk4?si=bc2182973d734447&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Selecionei algumas can\u00e7\u00f5es da plataforma\u00a0Groover\u00a0que voc\u00ea n\u00e3o pode deixar de ouvir, confira abaixo: 1 &#8211; ANYMEN &#8211; &#8216;Ghost Story&#8217;: O DJ e m\u00fasico eletr\u00f4nico franc\u00eas Tony Bouilly produz synthwave \/ retrowave electro sob o pseud\u00f4nimo ANYMEN, uma palavra inventada que simboliza a energia e o impacto que qualquer homem pode trazer para a equa\u00e7\u00e3o global, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202686,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11936,154],"tags":[11937,3579,9710],"class_list":["post-202670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-groover","category-musica","tag-groover","tag-lista","tag-musica-2"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/202670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=202670"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/202670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/202686"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=202670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=202670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=202670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}