{"id":209312,"date":"2024-05-03T18:56:42","date_gmt":"2024-05-03T21:56:42","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=209312"},"modified":"2024-05-03T18:56:46","modified_gmt":"2024-05-03T21:56:46","slug":"bamboo-br-faz-critica-a-ia-em-pressa","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/bamboo-br-faz-critica-a-ia-em-pressa\/","title":{"rendered":"Destaque do Reggae, Bamboo BR faz cr\u00edtica \u00e0 IA em \u201cPressa\u201d"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Em um mundo contempor\u00e2neo em que a intelig\u00eancia artificial vem dominando tudo e fazendo com que os dias pare\u00e7am ainda mais corridos, a banda paulista de Reggae, a <strong><a href=\"https:\/\/portalpopmais.com.br\/en\/bamboo-br-lanca-meu-bom-lugar\/\" data-type=\"post\" data-id=\"180934\">Bamboo BR<\/a><\/strong> apresenta \u201cPressa\u201d, um single que conta com a participa\u00e7\u00f5es de\u00a0<strong>Regiane Cordeiro<\/strong>\u00a0e\u00a0<strong>Bighetti<\/strong>, para protestar e alertar sobre a press\u00e3o, anseio e velocidade da vida moderna da atualidade. A can\u00e7\u00e3o chega aos apps de m\u00fasica nesta sexta-feira (3), com clipe no Youtube.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O novo som da banda \u00e9 dividido em tr\u00eas partes, com uma atmosfera sonora pr\u00f3pria para cada compositor entregar a sua voz e recado sobre os dias corridos. Al\u00e9m disso, a produ\u00e7\u00e3o musical ficou a cargo de Henrique Lanza, da AudioHouse Studio, e Ade, o vocalista da Bamboo BR.&nbsp;&nbsp;O videoclipe tem dire\u00e7\u00e3o de&nbsp;<strong>Ygor Carvalho,&nbsp;<\/strong>que trabalhou com nomes como<strong>&nbsp;Mano Brown, Flora Mattos e DJ KL Jay<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ade, inclusive, contou que o foco da nova m\u00fasica n\u00e3o \u00e9 somente a imers\u00e3o nos problemas que a intelig\u00eancia artificial tem para a vida cotidiana, mas, sim, para as conex\u00f5es genu\u00ednas e amorosas entre todos. \u201cQuestiono tamb\u00e9m a sinceridade daqueles que s\u00e3o bons em dar tapinhas nas costas, enquanto secretamente falam mal de voc\u00ea. Mas, mais do que simplesmente lamentar essa realidade, \u201cPressa\u201d \u00e9 um convite ao ouvinte a refletir sobre a import\u00e2ncia de desacelerar, de priorizar o que realmente importa e de cultivar conex\u00f5es genu\u00ednas\u201d, conta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 Bighetti revelou que focou sua parte como uma cr\u00edtica contra invejosos e as maldades que vem a partir deste sentimento. \u201cA formiga sempre sabe a folha que vai cortar. Minha av\u00f3 dizia com frequ\u00eancia que mesmo diante de uma grande adversidade, confiar nos nossos instintos \u00e9 extremamente necess\u00e1rio\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Regiane Cordeiro, que j\u00e1 dividiu vocais com\u00a0<strong>Marina Peralta<\/strong>\u00a0e\u00a0<strong>Da Ghama,<\/strong>\u00a0<strong>ex-guitarrista do Cidade Negra,<\/strong>\u00a0evocou sua ancestralidade para se conectar com o sentimento agridoce de ser uma cantora independente no Brasil. \u201cQuando compus minha parte na letra de \u201cPressa\u201d, mostrei exatamente como me sinto protegida de forma totalmente ancestral, para encarar as dores e del\u00edcias de ser uma cantora independente no Brasil&#8221;.<\/p>","protected":false},"excerpt":{"rendered":"<p>Em um mundo contempor\u00e2neo em que a intelig\u00eancia artificial vem dominando tudo e fazendo com que os dias pare\u00e7am ainda mais corridos, a banda paulista de Reggae, a Bamboo BR apresenta \u201cPressa\u201d, um single que conta com a participa\u00e7\u00f5es de\u00a0Regiane Cordeiro\u00a0e\u00a0Bighetti, para protestar e alertar sobre a press\u00e3o, anseio e velocidade da vida moderna da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":209313,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[4115,9710,16455],"class_list":["post-209312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-bamboo-br","tag-musica-2","tag-pressa"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/209312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=209312"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/209312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/209313"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=209312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=209312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=209312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}