{"id":213316,"date":"2024-07-05T06:33:12","date_gmt":"2024-07-05T09:33:12","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=213316"},"modified":"2024-07-05T06:33:41","modified_gmt":"2024-07-05T09:33:41","slug":"letra-mo-tempao-que-tu-nao-fala-comigo-oruam-mc-ryan-sp-kotim","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/letra-mo-tempao-que-tu-nao-fala-comigo-oruam-mc-ryan-sp-kotim\/","title":{"rendered":"Letra: &#8216;M\u00f3 Temp\u00e3o Que Tu N\u00e3o Fala Comigo&#8217; &#8211; Oruam, MC Ryan SP &#038; Kotim"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Nesta sexta-feira (5), <strong><a href=\"https:\/\/portalpopmais.com.br\/en\/rapper-oruam-e-preso-em-portugal\/\" data-type=\"post\" data-id=\"212695\">Oruam<\/a><\/strong>, MC Ryan Sp, Kotin e MC Don Juan lan\u00e7aram a faixa &#8216;<a href=\"https:\/\/youtu.be\/tGDV29ei4BE\" target=\"_blank\" rel=\"noopener\">M\u00f3 Temp\u00e3o Que Tu N\u00e3o Fala Comigo<\/a>&#8216;.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"M\u00d3 TEMP\u00c3O QUE TU N\u00c3O FALA COMIGO - Oruam, RYAN SP, IG, Don Juan, PH, Vulgo FK, Paiva, Luuky, Kotim\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/tGDV29ei4BE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Letra<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 o Kotim, ent\u00e3o pega a vis\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amor, &#8216;c\u00ea deixou o maloqueiro aqui<br>Foi embora sem se despedir (Uh, uh)<br>Faz m\u00f3 tempo, ainda t\u00f4 sozin&#8217; (Oh, oh)<br>S\u00f3 t\u00e1 eu, meu cachorro e o finin&#8217;<br>Netflix n\u00e3o liga pra mim (N\u00e3o, n\u00e3o)<br>T\u00f4 jogado na rua sozin&#8217;<br>Mas calma a\u00ed, porra, n\u00e3o \u00e9 s\u00f3 assim tamb\u00e9m<br>Ah, cora\u00e7\u00e3o vazio desde quando voc\u00ea foi embora<br>Sumiu, deixou o maloqueiro em prantos<br>Acendo uma bomba de ice pra ficar \u00e0 pampa<br>Saudade t\u00e1 apertando e eu finjo nem t\u00e1 ligando<br>Noventa e nove por cento do tempo penso em voc\u00ea<br>E outros um por cento desconto nas vagabunda&#8217;<br>De balada em balada, tentando te esqu\u0435cer<br>Enquanto n\u00e3o acontece, \u0435u sigo pagando essas puta&#8217;<br>Eu sigo meus dias sem voc\u00ea<br>N\u00e3o t\u00f4 te implorando, se quiser voltar, &#8216;c\u00ea volta<br>S\u00f3 acho que eu n\u00e3o sou mais o mesmo nesse rol\u00ea<br>Minha m\u00e3e t\u00e1 me ligando: &#8220;Filho, quando voc\u00ea volta?&#8221;<br>Porque \u00e9 v\u00e1rias balada&#8217;, noitada<br>Quinze dia&#8217;, eu t\u00f4 louco na presepada<br>J\u00e1 esqueci o endere\u00e7o da minha casa<br>O Waze calculando a rota, Angra dos Reis \u00e9 revoada, tchau<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00f3 temp\u00e3o que tu n\u00e3o fala comigo<br>Por qu\u00ea? J\u00e1 &#8216;tava acostumando ser sozinho<br>E voc\u00ea olha pra mim com esse sorriso lindo<br>Com esse sorriso lindo, com esse sorriso lindo<br>Por favor me esquece<br>M\u00f3 temp\u00e3o que tu n\u00e3o fala comigo<br>Por qu\u00ea? J\u00e1 &#8216;tava acostumando ser sozin&#8217;<br>E voc\u00ea olha pra mim com esse sorriso lindo<br>Com esse sorriso lindo, com esse sorriso lindo<br>Por favor me esquece<br>Jogador camisa 7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8216;C\u00ea vai, eu fico como? E tamb\u00e9m vai meu sono<br>Esque\u00e7o o patrim\u00f4nio de muitos e muitos milh\u00f5es de reais<br>Oh, o danado do amor machuca o tum-tum do maloca<br>Ela descongelou e a vida falou: &#8220;E agora?&#8221;<br>Cad\u00ea as puta&#8217;? Cad\u00ea as tchuca&#8217;?<br>Cad\u00ea revuca? \u00c9 v\u00e1rios debate&#8217;<br>Ha, diagn\u00f3stico: tem zool\u00f3gico no bolso<br>Visando o \u00f3bvio, o mundo malicioso<br>Ent\u00e3o tira a calcinha da Victoria&#8217;s Secret<br>Baby, \u00e9 o \u00faltimo convite<br>O time D na su\u00edte<br>Sem despedida final, nossa vida \u00e9 novela triste<br>E, ent\u00e3o tira a calcinha da Victoria&#8217;s Secret<br>Baby, \u00faltimo convite<br>O time D na su\u00edte<br>Sem despedida final, nossa vida \u00e9 novela triste e, \u00f3<br>Todo mundo odeia o IG, haha, ha, haha (Todo mundo odeia o IG)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amor (Amor), m\u00f3 temp\u00e3o que eu n\u00e3o te vejo (Que eu n\u00e3o te vejo)<br>Que vontade do seu beijo (Do seu beijo)<br>Vem matar os meus desejos<br>V\u00ea se n\u00e3o demora pra vim me trombar (Pra vim me trombar)<br>Que, se p\u00e1, pode me encontrar num bar ou sei l\u00e1 por onde tu vai me achar (Oh)<br>A vida \u00e9 muito louca e tu sumiu<br>S\u00f3 deixou as lembran\u00e7as e partiu (Partiu)<br>N\u00e3o sei o que fazer agora que meu peito chora, sei que pra minha dor n\u00e3o existe Doril (N\u00e3o)<br>Eu quero dist\u00e2ncia, mas sua presen\u00e7a me faz me sentir o Super-Man (Super-Man)<br>N\u00f3s fica maluco se n\u00f3s tamo&#8217; junto&#8217;, se passa uns minuto&#8217;, n\u00e3o tem (N\u00e3o)<br>Mas nada que te impe\u00e7a de gritar, de surtar, de pagar de maluca<br>Por isso que eu prefiro n\u00e3o ficar nem resmungar, s\u00f3 ligar e chamar umas puta&#8217; (E chamar)<br>Mas nada que te impe\u00e7a de gritar, de surtar, de pagar, de pagar de maluca<br>Por isso que eu prefiro n\u00e3o ficar nem resmungar, s\u00f3 ligar e chamar umas puta&#8217; (Yeah)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaidinha com a ex, de novo n\u00f3s se trombou<br>Rolou uma fita, mas na minha mente &#8216;c\u00ea ficou<br>As mem\u00f3ria&#8217; do bail\u00e3o, as viv\u00eancia&#8217;, minha rotina<br>Sa\u00ed chutado de l\u00e1, voltei pra essa putaria<br>Um brinde ao recome\u00e7o<br>Uma nova etapa na minha vida eu vou ter que come\u00e7ar<br>Eu sei bem o que eu mere\u00e7o<br>Mas n\u00e3o vai ser voc\u00ea que vai ter que apontar ou julgar, h\u00e3<br>Quebre um copo e tente juntar os cacos<br>H\u00e3, \u00e9 tipo assim que voc\u00ea fez com o meu cora\u00e7\u00e3o<br>Todas as fotos nos meus apagados<br>Ha, devolve agora os presente&#8217; da Louis Vuitton<br>Mais uma noite, me encontro em claro<br>Chave da Porsche, um ma\u00e7o de Carlton<br>Afogo as m\u00e1goas no u\u00edsque amadeirado<br>Odeio ser sozinho, \u00e9 sempre com as puta&#8217; do lado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00f3 temp\u00e3o que tu n\u00e3o fala comigo<br>Por qu\u00ea? J\u00e1 &#8216;tava acostumando ser sozinho<br>E voc\u00ea olha pra mim com esse sorriso lindo<br>Com esse sorriso lindo, com esse sorriso lindo<br>Por favor me esquece<br>Jogador camisa 7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cora\u00e7\u00e3o partido e eu n\u00e3o sei se isso vai passar<br>Me diz onde errei, o erro que eu cometi dessa vez s\u00f3 foi te amar<br>&#8216;C\u00ea brincou comigo e o mund\u00e3o, ele vai girar<br>Voc\u00ea vai voltar, &#8216;c\u00ea vai ver minha nova vers\u00e3o, &#8216;c\u00ea vai ficar triste por dentro, vai bater arrependimento e eu n\u00e3o vou voltar<br>Eu n\u00e3o sei se eu t\u00f4 no caminho certo<br>Chego do pi\u00e3o, minha casa vazia<br>&#8216;C\u00ea sabe que eu fiz de tudo pra dar certo<br>Tinha abandonado a putaria<br>Acho que ela n\u00e3o se importa de me ver com outras<br>J\u00e1 me superou, t\u00e1 vivendo a vida<br>N\u00e3o encosta nos rol\u00ea&#8217; que a gente frequentava<br>Que, quando ela me tromba, ela tem uma reca\u00edda<br>Cora\u00e7\u00e3o partido e eu n\u00e3o sei se isso vai passar<br>Me diz onde errei, o erro que eu cometi dessa vez s\u00f3 foi te amar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noite, balada, bebida e brisa, olha os louco&#8217; em Ibiza<br>Aonde as beb\u00ea&#8217; localiza<br>Tra\u00e7ando o camin&#8217; que a gente pisa<br>Volks&#8217; \u00e9 carro de vigarista<br>Com essa decep\u00e7\u00e3o e o desapego, eu lembrei de uns fato&#8217;<br>Troquei o meu cora\u00e7\u00e3o, cora\u00e7\u00e3o n\u00e3o, ficou s\u00f3 os caco&#8217;<br>Hoje eu t\u00f4 regenerado de uma rela\u00e7\u00e3o no passado<br>\u00c9 s\u00f3 marcha que n\u00f3s taca e o sofrimento n\u00f3s deixa de lado<br>Amor, a dor<br>J\u00e1 doeu no peito, eu desapeguei, n\u00e3o teve mais jeito<br>Vou voltar pra putaria mesmo<br>Amor, a dor<br>J\u00e1 doeu no peito, eu desapeguei, n\u00e3o teve mais jeito<br>Vou voltar pra putaria mesmo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Talvez a gente n\u00e3o se entende mais (Yeah) e nem se fala mais (Ahn)<br>Nem sei quanto tempo faz (N\u00e3o) que eu n\u00e3o tiro sua paz<br>E n\u00f3s n\u00e3o divide o ice (N\u00e3o), e pra voc\u00ea, tanto faz (Ahn)<br>Dizer que agora vai embora e sem olhar pra tr\u00e1s<br>Talvez seu jeito de mandona, marrenta na cama<br>Me faz querer sentir seu cheiro todo dia, te beijar todo dia<br>Sentir o cheiro da sua vag\u2014, provocar ci\u00fames nas suas amiga&#8217;<br>Desculpa as vezes que eu vacilei<br>E perdoa as vezes que eu te fiz chorar<br>Mas se p\u00e1 que seja melhor pra gente<br>N\u00e3o se encontrar mais<br>Desculpa as vezes que eu vacilei<br>E perdoa as vezes que eu te fiz chorar<br>Mas se p\u00e1 que seja melhor pra gente<br>N\u00e3o se encontrar mais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00f3 temp\u00e3o que tu n\u00e3o fala comigo<br>Por qu\u00ea? J\u00e1 &#8216;tava acostumando ser sozinho<br>E voc\u00ea olha pra mim com esse sorriso lindo<br>Com esse sorriso lindo, com esse sorriso lindo<br>Por favor me esquece<br>Jogador camisa 7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 o Kotim, ent\u00e3o pega a vis\u00e3o<\/p>","protected":false},"excerpt":{"rendered":"<p>Nesta sexta-feira (5), Oruam, MC Ryan Sp, Kotin e MC Don Juan lan\u00e7aram a faixa &#8216;M\u00f3 Temp\u00e3o Que Tu N\u00e3o Fala Comigo&#8216;. Letra \u00c9 o Kotim, ent\u00e3o pega a vis\u00e3o Amor, &#8216;c\u00ea deixou o maloqueiro aquiFoi embora sem se despedir (Uh, uh)Faz m\u00f3 tempo, ainda t\u00f4 sozin&#8217; (Oh, oh)S\u00f3 t\u00e1 eu, meu cachorro e o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":206552,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[11331],"class_list":["post-213316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-oruam"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/213316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=213316"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/213316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/206552"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=213316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=213316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=213316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}