{"id":234926,"date":"2025-07-01T11:28:21","date_gmt":"2025-07-01T14:28:21","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=234926"},"modified":"2025-07-01T11:28:25","modified_gmt":"2025-07-01T14:28:25","slug":"mc-hariel-inaugura-produtora-musical","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/mc-hariel-inaugura-produtora-musical\/","title":{"rendered":"\u00a0MC Hariel inaugura produtora cultural e amplia atua\u00e7\u00e3o no mercado musical"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O cantor <strong><a href=\"https:\/\/portalpopmais.com.br\/en\/trends\/mc-hariel\/\" data-type=\"post_tag\" data-id=\"4185\">MC Hariel<\/a><\/strong>\u00a0inaugurou hoje (1\u00ba\/7) a\u00a0<strong>Zaori<\/strong>, sua nova produtora cultural. O projeto nasce com a miss\u00e3o de promover a cultura, apoiar jovens artistas e oferecer contratos mais transparentes e positivos. A empresa ser\u00e1 respons\u00e1vel por gerenciar e profissionalizar os talentos que se destacarem no selo musical Xaolin Records, tamb\u00e9m criado por Hariel.<br>\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para brindar a novidade, o artista realiza, no mesmo dia do lan\u00e7amento, um coquetel de abertura do espa\u00e7o, exclusivo para convidados, com a exposi\u00e7\u00e3o de 20 obras de arte do projeto OPNI &#8211; coletivo de grafiteiros da zona leste de S\u00e3o Paulo, formado por aproximadamente 20 jovens da periferia.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"694\" src=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2025\/07\/image-2-1170x694.png\" alt=\"\" class=\"wp-image-234927\" title=\"\" srcset=\"https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2025\/07\/image-2-1170x694.png 1170w, https:\/\/portalpopmais.com.br\/wp-content\/uploads\/2025\/07\/image-2-768x456.png 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\">Foto: Renan Miranda<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">A empresa surge como uma plataforma de transforma\u00e7\u00e3o social e art\u00edstica. A ideia \u00e9 ampliar o acesso de jovens perif\u00e9ricos ao mercado da m\u00fasica, criando um ciclo de desenvolvimento: primeiro, os artistas ganham visibilidade e gravam pela Xaolin Records; depois, os que mais se destacarem ter\u00e3o a chance de assinar contratos profissionais com a nova produtora. A expectativa \u00e9 que a nova produtora amplie o alcance de projetos culturais e musicais ligados \u00e0 cultura da quebrada.<br>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m de apostar em novos talentos, a empresa refor\u00e7a o compromisso com contratos mais justos e com foco no desenvolvimento humano e art\u00edstico. &#8220;<em>Quero que os artistas que passem pela Zaori sintam que t\u00eam voz, espa\u00e7o e oportunidade de verdade. A ideia \u00e9 transformar vidas atrav\u00e9s da cultura<\/em>&#8220;, destaca MC Hariel.<\/p>","protected":false},"excerpt":{"rendered":"<p>O cantor MC Hariel\u00a0inaugurou hoje (1\u00ba\/7) a\u00a0Zaori, sua nova produtora cultural. O projeto nasce com a miss\u00e3o de promover a cultura, apoiar jovens artistas e oferecer contratos mais transparentes e positivos. A empresa ser\u00e1 respons\u00e1vel por gerenciar e profissionalizar os talentos que se destacarem no selo musical Xaolin Records, tamb\u00e9m criado por Hariel.\u00a0 Para brindar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":195753,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[4185],"class_list":["post-234926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-mc-hariel"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/234926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=234926"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/234926\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/195753"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=234926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=234926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=234926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}