{"id":237502,"date":"2025-07-18T15:11:43","date_gmt":"2025-07-18T18:11:43","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=237502"},"modified":"2025-07-18T15:12:33","modified_gmt":"2025-07-18T18:12:33","slug":"quem-e-mulher-expos-casal-show-coldplay","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/quem-e-mulher-expos-casal-show-coldplay\/","title":{"rendered":"Quem \u00e9 a tiktoker de 28 anos que viralizou ap\u00f3s expor amantes em show do Coldplay"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O v\u00eddeo viral registrado durante um show do <strong><a href=\"https:\/\/ikarus.mus.br\/?s=Coldplay\" target=\"_blank\" rel=\"noopener\">Coldplay<\/a><\/strong>, em Boston, nos Estados Unidos, segue repercutindo nas redes sociais. Nas imagens, um casal aparece no tel\u00e3o durante o momento conhecido como &#8220;c\u00e2mera do beijo&#8221;. Posteriormente, se descobriu que o homem, na verdade, \u00e9 Andy Byron, um poderoso CEO do ramo da tecnologia, e que estava no local com a sua amante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O v\u00eddeo, inicialmente compartilhado no TikTok, j\u00e1 possui mais de 50 milh\u00f5es de visualiza\u00e7\u00f5es. A respons\u00e1vel por gravar e postar o conte\u00fado foi a jovem Grace Springer, de 28 anos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grace \u00e9 geralmente discreta e usa seus perfis para copmpartilhar fotos de seu cachorro, momentos de viagem e de sua rotina de exerc\u00edcios. No Instagram, ela possui pouco mais de 3 mil seguidores, bem aqu\u00e9m dos n\u00fameros do v\u00eddeo viral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em entrevista ao The Sun, Springer comentou sobre a repercuss\u00e3o: <em>&#8220;Eu n\u00e3o fazia ideia de quem era o casal. S\u00f3 pensei que tinha visto uma rea\u00e7\u00e3o interessante na c\u00e2mera do beijo e decidi postar. Uma parte de mim se sente mal por virar a vida dessas pessoas de cabe\u00e7a para baixo&#8221;.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.instagram.com\/p\/DFWN9_-gIDN\/?utm_source=ig_embed&#038;ig_rid=74d03185-962c-4ae2-ad5c-3562a5cfd3c0\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Flagra no show do Coldplay<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O homem nas imagens \u00e9 Andy Byron, da empresa Astronomer. A mulher \u00e9 a chefe de RH de sua empresa, Kristin Cabot.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O v\u00eddeo do momento viralizou em v\u00e1rias plataformas, gerando memes, debates e tamb\u00e9m cr\u00edticas sobre os limites da exposi\u00e7\u00e3o p\u00fablica. O epis\u00f3dio levantou discuss\u00f5es sobre privacidade, especialmente quando situa\u00e7\u00f5es \u00edntimas acabam sendo exibidas sem consentimento em grandes eventos.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">Gente? Coldplay exp\u00f5e homem com sua amante durante tel\u00e3o do show. Nas redes sociais, os internautas investigaram o rapaz e n\u00e3o pouparam tempo em revelar a verdade: \u201cEle \u00e9 casado e tem dois filhos\u201d<a href=\"https:\/\/t.co\/S5L7rKT0G3\">pic.twitter.com\/S5L7rKT0G3<\/a><\/p>&mdash; Portal POP Mais (@sitepopmais) <a href=\"https:\/\/twitter.com\/sitepopmais\/status\/1945830235699642857?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 17, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>O v\u00eddeo viral registrado durante um show do Coldplay, em Boston, nos Estados Unidos, segue repercutindo nas redes sociais. Nas imagens, um casal aparece no tel\u00e3o durante o momento conhecido como &#8220;c\u00e2mera do beijo&#8221;. Posteriormente, se descobriu que o homem, na verdade, \u00e9 Andy Byron, um poderoso CEO do ramo da tecnologia, e que estava [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":237472,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[2466],"class_list":["post-237502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-coldplay"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/237502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=237502"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/237502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/237472"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=237502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=237502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=237502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}