{"id":242675,"date":"2025-08-09T18:27:40","date_gmt":"2025-08-09T21:27:40","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=242675"},"modified":"2025-08-09T18:27:43","modified_gmt":"2025-08-09T21:27:43","slug":"p-diddy-quer-virar-conselheiro-de-agressores-acusadoras-se-opoem","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/p-diddy-quer-virar-conselheiro-de-agressores-acusadoras-se-opoem\/","title":{"rendered":"P. Diddy quer virar conselheiro de agressores; acusadoras se op\u00f5em"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O suposto plano de Sean Combs, tamb\u00e9m conhecido como Diddy, para sair da cust\u00f3dia federal e aconselhar agressores de viol\u00eancia dom\u00e9stica est\u00e1 causando revolta entre suas acusadoras. \u201cIsso \u00e9 absolutamente absurdo\u201d, disse Douglas Wigdor, advogado especializado em direitos das v\u00edtimas que representa a ex-namorada de Combs, Casandra \u201cCassie\u201d Ventura, \u00e0 <em>Rolling Stone<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O coro de cr\u00edticas veio ap\u00f3s uma das advogadas de defesa de Combs, Alexandra Shapiro, dizer ao Business Insider que o fundador da Bad Boy Records espera se tornar um conselheiro contra a viol\u00eancia dom\u00e9stica \u201cpara ajudar de todas as formas poss\u00edveis, incentivando outras pessoas a n\u00e3o fazerem isso e ajudando realmente de maneira positiva no futuro\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gloria Allred, advogada que representa duas autoras de processos em andamento contra Combs, disse que o magnata condenado ainda tem um longo caminho antes de estar pronto at\u00e9 mesmo para considerar ser conselheiro. Ela tamb\u00e9m representa outras supostas v\u00edtimas que falaram com as autoridades e estavam na lista de poss\u00edveis testemunhas no julgamento criminal, mas que n\u00e3o foram chamadas a depor, segundo ela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>O suposto plano de Sean Combs, tamb\u00e9m conhecido como Diddy, para sair da cust\u00f3dia federal e aconselhar agressores de viol\u00eancia dom\u00e9stica est\u00e1 causando revolta entre suas acusadoras. \u201cIsso \u00e9 absolutamente absurdo\u201d, disse Douglas Wigdor, advogado especializado em direitos das v\u00edtimas que representa a ex-namorada de Combs, Casandra \u201cCassie\u201d Ventura, \u00e0 Rolling Stone. O coro de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":221342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[16879],"class_list":["post-242675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-p-diddy-2"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/242675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=242675"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/242675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/221342"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=242675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=242675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=242675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}