{"id":246019,"date":"2025-08-25T15:15:34","date_gmt":"2025-08-25T18:15:34","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=246019"},"modified":"2025-08-25T15:23:05","modified_gmt":"2025-08-25T18:23:05","slug":"taylor-swift-show-super-bowl-2026","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/taylor-swift-show-super-bowl-2026\/","title":{"rendered":"Taylor Swift \u00e9 cotada para show no intervalo do Super Bowl 2026"},"content":{"rendered":"<p><strong><a href=\"https:\/\/portalpopmais.com.br\/en\/trends\/taylor-swift\/\" data-type=\"post_tag\" data-id=\"411\">Taylor Swift<\/a><\/strong> \u00e9 a primeira escolha para se apresentar no Halftime Show do Super Bowl, marcado para o dia 8 de fevereiro de <strong><a href=\"https:\/\/www.instagram.com\/portalpopmais?igsh=MTNjb2tpbnRud3pqMw==\" target=\"_blank\" rel=\"noopener\">2026<\/a><\/strong>. A cantora seria a respons\u00e1vel por um grande show em um dos maiores eventos esportivos e televisivos do mundo.<\/p>\n\n\n\n<p>De acordo com a Billboard, a NFL estaria negociando com Swift para fechar sua participa\u00e7\u00e3o. Nos \u00faltimos anos, o intervalo do Super Bowl j\u00e1 contou com performances ic\u00f4nicas de artistas como Beyonc\u00e9, Shakira, Jennifer Lopez, Katy Perry, Madonna e Rihanna, se tornando um dos momentos mais aguardados do evento.<\/p>\n\n\n\n<p>Al\u00e9m da m\u00fasica, Taylor Swift mant\u00e9m uma rela\u00e7\u00e3o pr\u00f3xima com o esporte: ela namora Travis Kelce, jogador do Kansas City Chiefs, desde 2023, refor\u00e7ando sua conex\u00e3o com o universo do futebol americano.<\/p>\n\n\n\n<p>A artista tamb\u00e9m anunciou seu 12\u00ba \u00e1lbum de est\u00fadio, \u201cThe Life of a Showgirl\u201d, com lan\u00e7amento previsto para 13 de outubro. Caso participe do Super Bowl, \u00e9 esperado que ela inclua hits de toda a sua carreira, al\u00e9m de can\u00e7\u00f5es do novo projeto.<\/p>","protected":false},"excerpt":{"rendered":"<p>Taylor Swift \u00e9 a primeira escolha para se apresentar no Halftime Show do Super Bowl, marcado para o dia 8 de fevereiro de 2026. A cantora seria a respons\u00e1vel por um grande show em um dos maiores eventos esportivos e televisivos do mundo. De acordo com a Billboard, a NFL estaria negociando com Swift para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":246020,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154,173],"tags":[18550,411],"class_list":["post-246019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","category-celebridades","tag-destaque","tag-taylor-swift"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/246019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=246019"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/246019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/246020"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=246019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=246019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=246019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}