{"id":285699,"date":"2026-02-04T07:08:41","date_gmt":"2026-02-04T10:08:41","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=285699"},"modified":"2026-02-04T07:08:43","modified_gmt":"2026-02-04T10:08:43","slug":"luana-piovani-volta-detonar-globo","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/luana-piovani-volta-detonar-globo\/","title":{"rendered":"Luana Piovani critica Globo e relembra conflitos nos bastidores de novelas"},"content":{"rendered":"<p>A atriz <strong><a href=\"https:\/\/portalpopmais.com.br\/en\/trends\/luana-piovani\/\" data-type=\"post_tag\" data-id=\"5888\">Luana Piovani<\/a><\/strong> voltou a fazer duras cr\u00edticas \u00e0 TV Globo ao relembrar epis\u00f3dios do in\u00edcio de sua carreira na televis\u00e3o. Morando atualmente em Portugal, a artista falou sobre experi\u00eancias que classificou como traum\u00e1ticas e acusou a emissora de ter adotado posturas \u201cabusivas\u201d ap\u00f3s ela se recusar a assinar contratos de longa dura\u00e7\u00e3o.<\/p>\n\n\n\n<p>Segundo Piovani, os conflitos come\u00e7aram logo ap\u00f3s o sucesso de sua estreia em <em>Sex Appeal<\/em>. Na \u00e9poca, a <a href=\"http:\/\/globo.com\" target=\"_blank\" rel=\"noopener\">Globo<\/a> teria oferecido um contrato de exclusividade de tr\u00eas anos, atrelado \u00e0 participa\u00e7\u00e3o em uma novela, proposta que foi recusada pela atriz. \u201cQuando eu protagonizei <em>Sex Appeal<\/em>, a Globo chegou com um contrato longo para que os atores fizessem uma novela, e eu n\u00e3o quis o contrato de tr\u00eas anos\u201d, afirmou.<\/p>\n\n\n\n<p>A decis\u00e3o de priorizar a liberdade art\u00edstica, segundo ela, teria resultado em repres\u00e1lias internas. Luana relatou que passou a ser vista como uma profissional dif\u00edcil por n\u00e3o aceitar imposi\u00e7\u00f5es de agenda e regras que considerava excessivas. Um dos epis\u00f3dios mais marcantes, de acordo com seu relato, foi a sa\u00edda da novela <em>Anjo Mau<\/em>. \u201cForam super abusivos comigo\u201d, disse a atriz, ao contar que foi retirada da produ\u00e7\u00e3o sob a alega\u00e7\u00e3o de que estaria \u201cdesagregando\u201d a equipe por n\u00e3o se adequar aos hor\u00e1rios impostos pela emissora.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Maturidade e resist\u00eancia<\/h3>\n\n\n\n<p>Em entrevista \u00e0 jornalista Heloisa Tolipan, Piovani afirmou que, apesar do amadurecimento ao longo dos anos, sua postura firme permanece a mesma. \u201cN\u00e3o h\u00e1 diferen\u00e7a entre a Luana que come\u00e7ou na carreira e a atual. Mas hoje me sinto mais amadurecida, muito experiente\u201d, declarou.<\/p>\n\n\n\n<p>A atriz tamb\u00e9m destacou que construiu sua trajet\u00f3ria sem se submeter a esquemas de favores ou \u00e0 l\u00f3gica que chama de \u201cmonop\u00f3lios\u201d no meio art\u00edstico. Para ela, a independ\u00eancia sempre foi um valor inegoci\u00e1vel. \u201c\u00c9 muito tempo sendo assertiva e n\u00e3o me submetendo a grandes patr\u00f5es ou \u00e0 linha social de dever favores\u201d, afirmou.<\/p>\n\n\n\n<p>Por fim, Luana ressaltou que a seguran\u00e7a em suas escolhas vem da confian\u00e7a na pr\u00f3pria intui\u00e7\u00e3o, que define como um mecanismo essencial de defesa. \u201cHoje eu sei quando devo obedecer \u00e0 minha intui\u00e7\u00e3o imediatamente. Isso \u00e9 um sistema de defesa\u201d, concluiu.<\/p>","protected":false},"excerpt":{"rendered":"<p>A atriz Luana Piovani voltou a fazer duras cr\u00edticas \u00e0 TV Globo ao relembrar epis\u00f3dios do in\u00edcio de sua carreira na televis\u00e3o. Morando atualmente em Portugal, a artista falou sobre experi\u00eancias que classificou como traum\u00e1ticas e acusou a emissora de ter adotado posturas \u201cabusivas\u201d ap\u00f3s ela se recusar a assinar contratos de longa dura\u00e7\u00e3o. Segundo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":204591,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[18550,5888],"class_list":["post-285699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-destaque","tag-luana-piovani"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/285699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=285699"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/285699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/204591"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=285699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=285699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=285699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}