{"id":296531,"date":"2026-04-01T07:00:35","date_gmt":"2026-04-01T10:00:35","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=296531"},"modified":"2026-04-01T07:01:35","modified_gmt":"2026-04-01T10:01:35","slug":"namorado-da-mae-de-virginia-se-pronuncia-apos-flagra-em-prostibulo-na-rua","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/namorado-da-mae-de-virginia-se-pronuncia-apos-flagra-em-prostibulo-na-rua\/","title":{"rendered":"Namorado da m\u00e3e de Virginia Fonseca se pronuncia ap\u00f3s suposto flagra em \u201cprost\u00edbulo\u201d na rua"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O m\u00fasico Danilo Sanfoneiro, padrasto da influenciadora Virginia Fonseca, se manifestou ap\u00f3s ter seu nome envolvido em rumores nas redes sociais sobre uma suposta abordagem a mulheres em uma regi\u00e3o de Goi\u00e2nia conhecida pela presen\u00e7a de profissionais do sexo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo relatos, o epis\u00f3dio teria ocorrido h\u00e1 cerca de duas semanas, per\u00edodo em que a cidade recebia um grande evento esportivo. Testemunhas afirmaram que Danilo estaria em um carro com amigos quando passou por uma via conhecida por manter um \u201cprost\u00edbulo a c\u00e9u aberto\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com essas vers\u00f5es, ele teria sido reconhecido no local ao supostamente interagir com uma mulher. \u201cVoc\u00ea n\u00e3o \u00e9 o ex de Margareth?\u201d, teria questionado a pessoa, conforme relatos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Procurado para comentar o caso, Danilo apresentou outra vers\u00e3o. Ele confirmou que esteve na regi\u00e3o, mas negou qualquer abordagem direta \u00e0s mulheres ou envolvimento na situa\u00e7\u00e3o descrita. Segundo o m\u00fasico, quem teria interagido foram amigos que estavam com ele no ve\u00edculo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em declara\u00e7\u00e3o, ele detalhou o ocorrido e afirmou que tudo n\u00e3o passou de um mal-entendido:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe recordo sim e sabia que iriam procurar voc\u00eas. Estava voltando do futebol com os amigos e passamos na rua onde elas fazem programas e elas me reconheceu (sic) e ficou gritando mas eu nem cheguei a conversar com ningu\u00e9m n\u00e3o. Na verdade estava voltando do futebol, eu, meu ex-cunhado e um amigo, e eu n\u00e3o sabia que eles ia (sic) abordar essas mo\u00e7a (sic) fazendo brincadeira. Foi brincadeira deles, eles n\u00e3o tiveram maldade nem em me prejudicar nem em ofender as mo\u00e7as n\u00e3o. Quando elas come\u00e7aram a gritar meu nome l\u00e1, elas mesmas tavam levando na brincadeira, mas infelizmente todo mundo quer levar fama um em cima do outro\u201d, declarou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A repercuss\u00e3o acontece pouco tempo ap\u00f3s a reconcilia\u00e7\u00e3o de Danilo com Margareth Serr\u00e3o, m\u00e3e de Virginia. <a href=\"https:\/\/portalpopmais.com.br\/en\/mae-de-virginia-fonseca-reata-namoro-com-sanfoneiro\/\">O relacionamento havia sido retomado recentemente ap\u00f3s um per\u00edodo de separa\u00e7\u00e3o iniciado em dezembro do ano passado.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Margareth tamb\u00e9m se manifestou nas redes sociais, onde compartilhou uma mensagem de cunho religioso. \u201cObrigado Senhor pela paz que me deste. Pela f\u00e9 que me envolve, pela porta que abriste. S\u00f3 gratid\u00e3o. Am\u00e9m\u201d, escreveu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>M\u00fasico nega abordagem e diz que situa\u00e7\u00e3o foi \u201cbrincadeira\u201d de amigos ap\u00f3s ser citado em relatos sobre suposta intera\u00e7\u00e3o em \u00e1rea de prostitui\u00e7\u00e3o em Goi\u00e2nia.<\/p>","protected":false},"author":2,"featured_media":296414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[19881,7653],"class_list":["post-296531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-margareth-serrao","tag-virginia-fonseca"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/296531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=296531"}],"version-history":[{"count":3,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/296531\/revisions"}],"predecessor-version":[{"id":296534,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/296531\/revisions\/296534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/296414"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=296531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=296531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=296531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}