{"id":303167,"date":"2026-07-15T08:00:00","date_gmt":"2026-07-15T11:00:00","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=303167"},"modified":"2026-07-15T06:19:53","modified_gmt":"2026-07-15T09:19:53","slug":"jose-de-abreu-afirma-que-novo-imovel-de-virginia-veio-de-perdas-nas-bets","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/jose-de-abreu-afirma-que-novo-imovel-de-virginia-veio-de-perdas-nas-bets\/","title":{"rendered":"Jos\u00e9 de Abreu afirma que novo im\u00f3vel de Virginia veio de perdas nas bets"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O ator Jos\u00e9 de Abreu criticou a influenciadora Virginia Fonseca nas redes sociais ap\u00f3s a repercuss\u00e3o da not\u00edcia de que ela teria adquirido um apartamento de luxo avaliado em cerca de R$ 20 milh\u00f5es, em Santa Catarina. O im\u00f3vel estaria localizado no mesmo edif\u00edcio onde o jogador Neymar possui uma cobertura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em uma publica\u00e7\u00e3o no X (antigo Twitter), Jos\u00e9 de Abreu compartilhou a informa\u00e7\u00e3o sobre a compra e fez um coment\u00e1rio em refer\u00eancia \u00e0 investiga\u00e7\u00e3o envolvendo a influenciadora. &#8220;Dos 30% que ela ganha sobre o que voc\u00ea perde&#8221;, escreveu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A declara\u00e7\u00e3o faz alus\u00e3o \u00e0 a\u00e7\u00e3o civil p\u00fablica movida pelo Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios (MPDFT), que apura a participa\u00e7\u00e3o de Virginia em campanhas publicit\u00e1rias de plataformas de apostas esportivas. Segundo o Minist\u00e9rio P\u00fablico, a investiga\u00e7\u00e3o busca esclarecer se a influenciadora participou de um modelo de divulga\u00e7\u00e3o que previa o recebimento de uma comiss\u00e3o equivalente a 30% das perdas de usu\u00e1rios que acessassem as plataformas por meio de seus links.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O caso ganhou repercuss\u00e3o ap\u00f3s a divulga\u00e7\u00e3o de um v\u00eddeo em que Virginia comentava sobre uma aposta durante uma partida da Copa do Mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em depoimento prestado \u00e0 CPI das Bets, Virginia negou ter recebido qualquer remunera\u00e7\u00e3o baseada nas perdas dos apostadores. A influenciadora afirmou que seu contrato previa pagamento fixo, al\u00e9m de um b\u00f4nus atrelado ao desempenho financeiro da empresa contratante, e sustentou que nunca recebeu valores calculados sobre os preju\u00edzos de seus seguidores.<\/p>","protected":false},"excerpt":{"rendered":"<p>O ator Jos\u00e9 de Abreu criticou a influenciadora Virginia Fonseca nas redes sociais ap\u00f3s a repercuss\u00e3o da not\u00edcia de que ela teria adquirido um apartamento de luxo avaliado em cerca de R$ 20 milh\u00f5es, em Santa Catarina. O im\u00f3vel estaria localizado no mesmo edif\u00edcio onde o jogador Neymar possui uma cobertura. Em uma publica\u00e7\u00e3o no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":303168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-303167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fire2"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/303167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=303167"}],"version-history":[{"count":1,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/303167\/revisions"}],"predecessor-version":[{"id":303169,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/303167\/revisions\/303169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/303168"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=303167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=303167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=303167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}