{"id":58012,"date":"2020-07-06T18:36:24","date_gmt":"2020-07-06T21:36:24","guid":{"rendered":"https:\/\/portalpopmais.wpcomstaging.com\/?p=58012"},"modified":"2020-07-06T18:36:24","modified_gmt":"2020-07-06T21:36:24","slug":"claudia-leitte-confirma-any-gabrielly-do-now-united-leo-santana-lore-improta-bera-mc-zaac-hungria-e-dennis-dj-para-a-live-40ando-na-quarentena","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/claudia-leitte-confirma-any-gabrielly-do-now-united-leo-santana-lore-improta-bera-mc-zaac-hungria-e-dennis-dj-para-a-live-40ando-na-quarentena\/","title":{"rendered":"Claudia Leitte confirma Any Gabrielly do Now United, L\u00e9o Santana, Lore Improta, Bera, MC Zaac, Hungria e Dennis DJ para a live \u201c40ando na Quarentena\u201d"},"content":{"rendered":"<p>O anivers\u00e1rio de 40 anos de <strong>Claudia Leitte<\/strong> est\u00e1 chegando, \u00e9 nesta sexta-feira (10\/7) com direito a uma live de comemora\u00e7\u00e3o nomeada como <em>\u201c40ando na Quarentena\u201d<\/em>, que acontece a partir das 19h30, no canal oficial da cantora no Youtube. Claudia prepara muitas surpresas para festejar a data com o p\u00fablico, entre elas est\u00e3o algumas participa\u00e7\u00f5es especiais que dividir\u00e3o o microfone, cada um de sua casa, com a cantora. O fen\u00f4meno teen <strong>Any Gabrielly<\/strong> (do grupo Now United), <strong>L\u00e9o Santana<\/strong>, o funkeiro<strong> MC Zaac<\/strong>, o rapper<strong> Hungria Hip Hop<\/strong>, <strong>Lore Improta<\/strong>, <strong>Bera<\/strong> e <strong>Dennis DJ<\/strong> s\u00e3o os primeiros nomes confirmados. Vale lembrar que a live tamb\u00e9m possui engajamento solid\u00e1rio para arrecadar doa\u00e7\u00f5es em prol das institui\u00e7\u00f5es Amigos do Bem, Beleza Escondida e HAM, das quais Claudia \u00e9 madrinha.<\/p>\n<p>Contudo, antes do anivers\u00e1rio, a cantora realiza nesta ter\u00e7a-feira, dia 7 de julho, mais uma edi\u00e7\u00e3o anula do \u201cDia do Bolha\u201d, data em que festeja a rela\u00e7\u00e3o com os seus f\u00e3s. A data, escolhida por eles, \u00e9 devido ao carinho da cantora pelo n\u00famero 7. Neste ano, devido ao isolamento social, a cantora far\u00e1 um desafio de conversar com 40 f\u00e3s (alus\u00e3o ao seu anivers\u00e1rio) durante uma live especial em seu Instagram agendada para acontecer a partir das 17h. Ao final, Claudia cantar\u00e1 uma m\u00fasica surpresa em homenagem a todos os f\u00e3s dando sequ\u00eancia ao esquenta da live \u201c40ando na Quarentena\u201d.<\/p>\n<p><strong>Agenda:<\/strong><\/p>\n<p><strong>Live \u201cDia do Bolha\u201d<\/strong><br \/>\nOnde: Instagram @ClaudiaLeitte &#8211; https:\/\/www.instagram.com\/claudialeitte<br \/>\nQuando: Ter\u00e7a-feira, dia 7 de julho, a partir das 17h<\/p>\n<p><strong>Live \u201c40ando na Quarentena\u201d<\/strong><br \/>\nOnde: Youtube da Claudia Leitte &#8211; https:\/\/www.youtube.com\/claudialeitte<br \/>\nQuando: Sexta-feira, dia 10 de julho, a partir das 19h30<\/p>","protected":false},"excerpt":{"rendered":"<p>O anivers\u00e1rio de 40 anos de Claudia Leitte est\u00e1 chegando, \u00e9 nesta sexta-feira (10\/7) com direito a uma live de comemora\u00e7\u00e3o nomeada como \u201c40ando na Quarentena\u201d, que acontece a partir das 19h30, no canal oficial da cantora no Youtube. Claudia prepara muitas surpresas para festejar a data com o p\u00fablico, entre elas est\u00e3o algumas participa\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":58017,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[155],"class_list":["post-58012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-claudia-leitte"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/58012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=58012"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/58012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=58012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=58012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=58012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}