{"id":60153,"date":"2020-07-24T14:51:34","date_gmt":"2020-07-24T17:51:34","guid":{"rendered":"https:\/\/portalpopmais.wpcomstaging.com\/?p=60153"},"modified":"2020-07-24T14:51:34","modified_gmt":"2020-07-24T17:51:34","slug":"segunda-edicao-do-festival-live-to-live-discute-o-pos-pandemia","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/segunda-edicao-do-festival-live-to-live-discute-o-pos-pandemia\/","title":{"rendered":"Segunda edi\u00e7\u00e3o do Festival Live To Live discute o p\u00f3s pandemia"},"content":{"rendered":"<p dir=\"ltr\">A segunda edi\u00e7\u00e3o do Festival <strong>#LiveToLive<\/strong> discute temas pertinentes para nos fazer refletir sobre o p\u00f3s pandemia. Em parceria com o portal <strong>Mais Brasil<\/strong>, o evento online organizado pelo jornalista e p\u00f3s graduando em marketing digital Wesley Mesquita (FAAP-SP) e pela artista e doutoranda Amanda Marques (PUC-SP), apresenta uma s\u00e9rie de bate-papos com artistas e intelectuais das mais diversas \u00e1reas para somar na discuss\u00e3o sobre o &#8220;p\u00f3s apocalipse&#8221;. Entre os dias 29 de Julho a 02 de Agosto, as lives-entrevistas acontecem no per\u00edodo da tarde, organizadas por dia e seus respectivos temas.<\/p>\n<p dir=\"ltr\">A partir disso, em conjunto, nos questionamos sobre: &#8220;e o que ser\u00e1 de n\u00f3s quando tudo isso acabar?&#8221;, e resolvemos oferecer c\u00e1psulas di\u00e1rias para que, de maneira conjunta e coletiva, possamos pensar em como a vida ser\u00e1 depois, se algo realmente de fato mudou ou mudar\u00e1; como podemos aliviar as tens\u00f5es dos nossos corpos, de onde podemos tirar um fio de esperan\u00e7a, e utilizar da m\u00fasica, da arte, e da literatura como fonte de ressignifica\u00e7\u00e3o do dia a dia.<\/p>\n<p dir=\"ltr\">Come\u00e7amos com um &#8220;esquenta&#8221; para o festival, lan\u00e7ando a hashtag #C\u00e1psulasApocal\u00edpticas que traz o depoimento de alguns internautas contando o que guardariam em uma c\u00e1psula do tempo caso o mundo acabasse, entre eles Rosana Hermann, Narcisa Tamborindeguy, Luiza Caspary, Pedro Palma, S\u00e3o Yant\u00f3 e Salma J\u00f4 da banda Carne Doce.<\/p>\n<p dir=\"ltr\">A cantora Paula Lima estr\u00e9ia a abertura na quarta-feira (dia 29\/07), em seguida acontece um bate-papo com a terapeura Katia Ananda (Santa Consci\u00eancia). Na quinta-feira (dia 30\/07) Rhaissa Bittar fala sobre as possibilidades da &#8220;vida depois&#8221; da pandemia. Sexta (dia 31\/07) Mia Badgyal e Jup do Bairro falam sobre corpos n\u00e3o bin\u00e1rios e transgressores.<\/p>\n<div id=\"attachment_60155\" style=\"width: 1190px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-60155\" class=\"size-full wp-image-60155\" src=\"https:\/\/portalpopmais.wpcomstaging.com\/wp-content\/uploads\/2020\/07\/FAAP294_PING_02-e1504041220915-1180x715-1.jpg\" alt=\"\" width=\"1180\" height=\"715\" title=\"\"><p id=\"caption-attachment-60155\" class=\"wp-caption-text\">(A psicanalista Maria Homem faz uma leitura de &#8220;Perdoando Deus&#8221; em homenagem aos 100 anos de Clarice Lispector)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">S\u00e1bado (dia 01\/08) a artista e escritora Cris Rangel (Editora Lyra das Artes) aborda o tema Produ\u00e7\u00e3o Cultural e Pol\u00edticas P\u00fablicas, em seguida Sarah Shrioder presta uma homenagem \u00e0 mem\u00f3ria da escritora e roteirista Fernanda Young. Para fechar o s\u00e1bado, a Professora Maria Homem, compartilha um pouco de sua extensa pesquisa ao fazer uma leitura em homenagem ao centen\u00e1rio de Clarice Lispector, mostrando-nos como a literatura \u00e9 importante em tempos t\u00e3o sombrios.<\/p>\n<p dir=\"ltr\">Domingo (02\/08), o \u00faltimo dia do festival recebe MC Tha e Alice Caymmi, falando sobre o artista independente em tempos de isolamento. O encerramento fica por conta da cantora K\u00e9sia Est\u00e1cio (Elza O Musical, T\u00e1 No Ar\/TV Globo) com um pocket-show especial.<\/p>\n<p dir=\"ltr\">A primeira edi\u00e7\u00e3o do web-festival aconteceu em mar\u00e7o com Filipe Catto, Carne Doce, Prettos, Romero Ferro, Davi Bandeira, Ekena, Kastrup, Rafa Mon, D\u00e9borah dos Falsetes, entre outros. Confira o programa completo da segunda edi\u00e7\u00e3o, e prepare-se para o &#8220;p\u00f3s-apocalipse&#8221;:<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\"><strong>PROGRAMA<\/strong><\/p>\n<p dir=\"ltr\">Mediador das lives: Wesley Mesquita (Jornalista)<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\"><strong>Quarta &#8211; 29\/07<\/strong><\/p>\n<p dir=\"ltr\">Tema: Estar conectado o tempo todo supre nossas car\u00eancias atuais, e depois?<\/p>\n<p dir=\"ltr\">15h &#8211; Abertura<\/p>\n<p dir=\"ltr\">17h &#8211; Paula Lima<\/p>\n<p dir=\"ltr\">19h &#8211; Katia Ananda (Santa Consci\u00eancia)<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\"><strong>Quinta &#8211; 30\/07<\/strong><\/p>\n<p dir=\"ltr\">Tema: Mem\u00f3ria, m\u00eddias e a vida depois<\/p>\n<p dir=\"ltr\">15h &#8211; Sarah Shrioder homenageia Fernanda Young<\/p>\n<p dir=\"ltr\">17h &#8211; Rhaissa Bittar<\/p>\n<p dir=\"ltr\">20h &#8211; Bia Bem &#8211; Novos formatos de m\u00eddia<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\"><strong>Sexta &#8211; 31\/07<\/strong><\/p>\n<p dir=\"ltr\">Tema: Transgress\u00e3o do corpo como arte<\/p>\n<p dir=\"ltr\">15h &#8211; Mia Badgyal &#8211; Corpos n\u00e3o bin\u00e1rios<\/p>\n<p dir=\"ltr\">17h &#8211; Jup do Bairro &#8211; Corpos Transgressores<\/p>\n<p dir=\"ltr\">19h &#8211; Amanda Marques &#8211; Performatividade e corpos (Im)poss\u00edveis<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\"><strong>S\u00e1bado\u00a0 &#8211; 01\/08<\/strong><\/p>\n<p dir=\"ltr\">Tema: Literatura como ref\u00fagio do caos<\/p>\n<p dir=\"ltr\">15h &#8211; Cris Rangel (Lyra das Artes) Produ\u00e7\u00e3o Cultural e Pol\u00edticas P\u00fablicas<\/p>\n<p dir=\"ltr\">17h &#8211; Karina Buhr &#8211;<\/p>\n<p dir=\"ltr\">19h &#8211; Maria Homem &#8211; 100 Anos de Clarice Lispector<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\"><strong>Domingo &#8211; 02\/08<\/strong><\/p>\n<p dir=\"ltr\">Artista Independente x Isolamento Social<\/p>\n<p dir=\"ltr\">15h &#8211; MC Tha<\/p>\n<p dir=\"ltr\">17h &#8211; Alice Caymmi<\/p>\n<p dir=\"ltr\">19h &#8211; K\u00e9sia Est\u00e1cio (Pocket de encerramento)<\/p>","protected":false},"excerpt":{"rendered":"<p>A segunda edi\u00e7\u00e3o do Festival #LiveToLive discute temas pertinentes para nos fazer refletir sobre o p\u00f3s pandemia. Em parceria com o portal Mais Brasil, o evento online organizado pelo jornalista e p\u00f3s graduando em marketing digital Wesley Mesquita (FAAP-SP) e pela artista e doutoranda Amanda Marques (PUC-SP), apresenta uma s\u00e9rie de bate-papos com artistas e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":60158,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2293],"tags":[],"class_list":["post-60153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/60153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=60153"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/60153\/revisions"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=60153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=60153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=60153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}