{"id":79763,"date":"2021-03-30T14:04:13","date_gmt":"2021-03-30T17:04:13","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=79763"},"modified":"2021-03-30T14:04:17","modified_gmt":"2021-03-30T17:04:17","slug":"pele-milflows-video-o-final","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/pele-milflows-video-o-final\/","title":{"rendered":"Revela\u00e7\u00e3o do rap, Pel\u00e9 MilFlows grava live session com a 48K"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Do chuveiro aos palcos, <a href=\"https:\/\/www.instagram.com\/pele.milflows\/\" target=\"_blank\" aria-label=\"Pel\u00e9 MilFlows (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"rank-math-link\"><strong>Pel\u00e9 MilFlows<\/strong><\/a> surgiu das Batalhas de MCs no Rio de Janeiro e ficou conhecido como <em>MilFlows<\/em> por conta do seu estilo vers\u00e1til de rimar, seja mel\u00f3dico, seja falado. O cantor e compositor foi convidado para gravar uma <em>live session <\/em>de sua can\u00e7\u00e3o <em>&#8220;O Final&#8221;<\/em> para o projeto <strong><em><a href=\"https:\/\/portalpopmais.com.br\/en\/gabi-luthai-regrava-paciencia\/\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"rank-math-link\">48K Apresenta<\/a><\/em><\/strong><em>,<\/em> que j\u00e1 trouxe nomes como Gabi Luthai, MAR ABERTO e Sabrina Lopes. &#8220;Foi demais participar desse projeto, &#8216;O Final&#8217; \u00e9 um som bem especial. Dar uma nova roupagem pra esse som em uma pegada bem org\u00e2nica foi incr\u00edvel&#8221;, conta Pel\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A can\u00e7\u00e3o original, que j\u00e1 soma mais de 700 mil visualiza\u00e7\u00f5es no YouTube, simboliza um amor que, mesmo com os problemas comuns de uma rela\u00e7\u00e3o, ainda n\u00e3o pode acabar. O <strong><em>48K Apresenta<\/em><\/strong> convida cantores da nova gera\u00e7\u00e3o para grava\u00e7\u00f5es de <em>live sessions <\/em>com capta\u00e7\u00e3o ao vivo de forma intimista e din\u00e2mica. Desde janeiro, o projeto j\u00e1 lan\u00e7ou outros dois feats da 48K: <em>Ex-Amor<\/em> com MAR ABERTO e Sabrina Lopes e <em>Paci\u00eancia<\/em>, com Gabi Luthai. Os pr\u00f3ximos lan\u00e7amentos ainda v\u00e3o trazer nomes como S\u00f3Ciro, Sabrina Oliveira e Bia Marques.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A produtora 48K, que conta com assessoria art\u00edstico-musical de Julio Salinas (A&amp;R) e o duo de produtores e m\u00fasicos Raul Alaune e Mateus <em>&#8220;O Melo&#8221;<\/em>, foi respons\u00e1vel pela idealiza\u00e7\u00e3o do projeto audiovisual que foi lan\u00e7ado pelo selo 48K Records. <em>&#8220;A ideia \u00e9 produzir uma vers\u00e3o ac\u00fastica e ao vivo de uma m\u00fasica j\u00e1 lan\u00e7ada do artista convidado. Nosso prop\u00f3sito \u00e9 fazer um produto diferenciado, com um v\u00eddeo din\u00e2mico e \u00fanico que tenha \u00e1udio e performance captados ao vivo&#8221;<\/em>, conta Julio.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <em>48K Apresenta<\/em>, como \u00e9 intitulada a s\u00e9rie de live sessions, nasceu como consequ\u00eancia natural do processo de produ\u00e7\u00e3o musical do 48K Produ\u00e7\u00e3o Musical, que se firma cada vez mais como elemento criativo de performances, arranjos, refer\u00eancias, produ\u00e7\u00e3o e composi\u00e7\u00e3o. A marca registrada do Est\u00fadio \u00e9 a cria\u00e7\u00e3o de m\u00fasica de forma integral para diversos perfis de artistas e p\u00fablicos, com destaque para o trabalho desenvolvido com artistas como Mariana Nolasco, Gabi Luthai, MAR ABERTO, Sabrina Oliveira, Phil, Rebeq, Konai, Guil, Julia Rznd\u00a0 e Sabrina Lopes.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"48k Apresenta #03 - &quot;O FINAL&quot; - Pel\u00e9 MilFlows (Vers\u00e3o Ac\u00fastico)\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/g1gNQUMsI18?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Do chuveiro aos palcos, Pel\u00e9 MilFlows surgiu das Batalhas de MCs no Rio de Janeiro e ficou conhecido como MilFlows por conta do seu estilo vers\u00e1til de rimar, seja mel\u00f3dico, seja falado. O cantor e compositor foi convidado para gravar uma live session de sua can\u00e7\u00e3o &#8220;O Final&#8221; para o projeto 48K Apresenta, que j\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79764,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154,183],"tags":[8429,3743],"class_list":["post-79763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","category-videos","tag-48k-apresenta","tag-pele-milflows"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/79763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=79763"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/79763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/79764"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=79763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=79763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=79763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}