{"id":82234,"date":"2021-04-30T16:26:17","date_gmt":"2021-04-30T19:26:17","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=82234"},"modified":"2021-04-30T16:26:44","modified_gmt":"2021-04-30T19:26:44","slug":"band-confirma-faustao-a-partir-de-2022","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/band-confirma-faustao-a-partir-de-2022\/","title":{"rendered":"Band confirma retorno de Faust\u00e3o \u00e0 emissora a partir de 2022"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A apresentadora Catia Fonseca confirmou no &#8220;Melhor da Tarde&#8221; desta sexta-feira (30) que <a href=\"https:\/\/midiatico.portalpopmais.com.br\/2021\/04\/30\/apos-sair-da-globo-fausto-silva-acerta-contra-com-a-band\/\" class=\"rank-math-link\"><strong>Faust\u00e3o<\/strong><\/a> estar\u00e1 de volta \u00e0 Band ap\u00f3s 33 anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">Momento em que C\u00e1tia Fonseca anuncia a contrata\u00e7\u00e3o do Faust\u00e3o na Band no <a href=\"https:\/\/twitter.com\/hashtag\/MelhorDaTarde?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#MelhorDaTarde<\/a>, lendo a nota escrita pelo pr\u00f3prio Saad <a href=\"https:\/\/t.co\/qYTV5twoZ7\">pic.twitter.com\/qYTV5twoZ7<\/a><\/p>&mdash; Feluma (@fernandoluiiz) <a href=\"https:\/\/twitter.com\/fernandoluiiz\/status\/1388199756313333761?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 30, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais cedo, o colunista do R7, Flavio Ricco, j\u00e1 havia dado a possibilidade do apresentador assinar um contrato de cinco anos com a emissora paulista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Embora C\u00e1tia j\u00e1 tenha confirmado a ida de Faust\u00e3o \u00e0 Band, a diretoria do canal foi ponderada e respondeu as especula\u00e7\u00f5es dizendo que o contrato ainda n\u00e3o foi assinado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Em rela\u00e7\u00e3o \u00e0s not\u00edcias publicadas hoje que anunciam o retorno de Fausto Silva \u00e0 Band em janeiro, a emissora informa que, uma vez confirmado, trata-se de um sonho antigo do Grupo Bandeirantes, que sempre admirou seu car\u00e1ter \u00e9tico, seu talento e seu jeito de inovar e fabricar sucesso.&#8221;, disse a emissora em comunicado enviado \u00e0 imprensa.<\/p>","protected":false},"excerpt":{"rendered":"<p>A apresentadora Catia Fonseca confirmou no &#8220;Melhor da Tarde&#8221; desta sexta-feira (30) que Faust\u00e3o estar\u00e1 de volta \u00e0 Band ap\u00f3s 33 anos. Momento em que C\u00e1tia Fonseca anuncia a contrata\u00e7\u00e3o do Faust\u00e3o na Band no #MelhorDaTarde, lendo a nota escrita pelo pr\u00f3prio Saad pic.twitter.com\/qYTV5twoZ7 &mdash; Feluma (@fernandoluiiz) April 30, 2021 Mais cedo, o colunista do [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":82235,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1152,7986],"class_list":["post-82234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fire2","tag-band","tag-faustao"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/82234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=82234"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/82234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/82235"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=82234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=82234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=82234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}