{"id":83253,"date":"2021-05-16T21:47:56","date_gmt":"2021-05-17T00:47:56","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=83253"},"modified":"2021-05-17T12:13:33","modified_gmt":"2021-05-17T15:13:33","slug":"morre-mc-kevin","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/morre-mc-kevin\/","title":{"rendered":"Morre MC Kevin, aos 23 anos, ap\u00f3s cair de varanda de hotel de luxo no RJ"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O funkeiro<strong> <a aria-label=\" (opens in a new tab)\" href=\"http:\/\/instagram.com\/mckevin\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"rank-math-link\">MC Kevin<\/a><\/strong> faleceu neste domingo (16) ap\u00f3s cair da varanda do 5\u00b0 andar de um hotel de luxo, no Rio de Janeiro. A morte do artista foi confirmada por agentes policiais. Kevin, que deu entrada no hospital em estado grav\u00edssimo, teve duas paradas cardiorrespirat\u00f3rias e n\u00e3o resistiu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O MC estava no Rio acompanhado da esposa, Deolane Bezerra &#8211; com quem havia casado h\u00e1 tr\u00eas semanas. Na noite de s\u00e1bado (15), ele se apresentou em uma balada chamada &#8216;Baile do Imperador&#8217;. <\/p>\n\n\n\n<pre class=\"wp-block-verse has-text-align-center\"><strong>Veja tamb\u00e9m\n<a aria-label=\"Um m\u00eas antes de morrer, MC Kevin lan\u00e7ou a faixa &quot;Minha \u00daltima M\u00fasica&quot; (opens in a new tab)\" href=\"https:\/\/portalpopmais.com.br\/en\/mc-kevin-ultima-musica\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"rank-math-link\">Um m\u00eas antes de morrer, MC Kevin lan\u00e7ou a faixa \"Minha \u00daltima M\u00fasica\"<\/a><\/strong><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s ele dar entrada no centro m\u00e9dico, antes da confirma\u00e7\u00e3o da morte, a Secretaria Municipal de Sa\u00fade informou que o estado de sa\u00fade do funkeiro era cr\u00edtico: <em>\u201cO paciente Kevin Bueno deu entrada no Hospital Municipal Miguel Couto e seu estado de sa\u00fade \u00e9 considerado muito grave\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um v\u00eddeo que circula nas redes sociais mostra o momento em que Kevin \u00e9 socorrido. Veja abaixo:<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">Ao que tudo indica, Mc Kevin acabou de pular do quinto andar de um pr\u00e9dio, estamos atr\u00e1s de mais informa\u00e7\u00f5es para falar com voc\u00eas da melhor forma! J\u00e1 entramos em contato com algumas pessoas pr\u00f3ximas a ele e j\u00e1 atualizo aqui! Esperamos que nada tenha acontecido <a href=\"https:\/\/t.co\/FS18FHLm72\">pic.twitter.com\/FS18FHLm72<\/a><\/p>&mdash; Garoto do blog (@garotxdoblogofc) <a href=\"https:\/\/twitter.com\/garotxdoblogofc\/status\/1394066879971569671?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 16, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">MC Kevin era um dos principais nomes do funk na atualidade. Entre seus principais sucessos est\u00e1 a faixa &#8220;Pra Inveja \u00c9 Tchau&#8221;, de 2019, que soma mais de 220 milh\u00f5es de reprodu\u00e7\u00f5es nas plataformas digitais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recentemente ele havia exposto sua insatisfa\u00e7\u00e3o com a produtora GR6, a qual possu\u00eda contrato, e chegou a amea\u00e7ar deixar a empresa, mas acabou voltando atr\u00e1s.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"MC Kevin e MC Davi - Pra Inveja \u00e9 Tchau (GR6 Filmes) Perera DJ\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/WMCKKUvwBCQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>O funkeiro MC Kevin faleceu neste domingo (16) ap\u00f3s cair da varanda do 5\u00b0 andar de um hotel de luxo, no Rio de Janeiro. A morte do artista foi confirmada por agentes policiais. Kevin, que deu entrada no hospital em estado grav\u00edssimo, teve duas paradas cardiorrespirat\u00f3rias e n\u00e3o resistiu. O MC estava no Rio acompanhado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83254,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[2163,2269],"class_list":["post-83253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","tag-capa","tag-mc-kevin"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/83253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=83253"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/83253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/83254"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=83253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=83253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=83253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}