{"id":91129,"date":"2021-09-02T21:36:40","date_gmt":"2021-09-03T00:36:40","guid":{"rendered":"https:\/\/portalpopmais.com.br\/?p=91129"},"modified":"2021-09-02T21:38:32","modified_gmt":"2021-09-03T00:38:32","slug":"juliette-lanca-primeiro-ep","status":"publish","type":"post","link":"https:\/\/portalpopmais.com.br\/en\/juliette-lanca-primeiro-ep\/","title":{"rendered":"Juliette lan\u00e7a seu primeiro EP; saiba tudo"},"content":{"rendered":"<p>Chegou o grande dia! J\u00e1 est\u00e1 dispon\u00edvel em todas as plataformas digitais o primeiro EP de <strong><a href=\"http:\/\/instagram.com\/juliette\" target=\"_blank\" rel=\"noreferrer noopener\">Juliette<\/a><\/strong>. O projeto foi desenvolvido como a primeira amostra musical da cantora e gravado entre as cidades do Rio de Janeiro, Salvador, Jo\u00e3o Pessoa e Recife. \u201cA m\u00fasica traduz sentimentos e d\u00e1 sentido \u00e0 vida. \u00c9 a fala da alma. A m\u00fasica \u00e9 uma forma po\u00e9tica de traduzir essa magia que \u00e9 o ser humano. Eu sou louca por m\u00fasica e agora estou tendo o tempo e a oportunidade para me dedicar a esse sonho e eu fico grata demais\u201d, diz Juliette.<\/p>\n\n\n\n<p>Esse \u00e9 o primeiro lan\u00e7amento da artista rec\u00e9m contratada pela Rodamoinho Records, em com a distribui\u00e7\u00e3o da Virgin Music Brasil. \u201cJuliette\u201d \u00e9 um EP com seis can\u00e7\u00f5es e que apresenta, em sua ficha t\u00e9cnica (em composi\u00e7\u00e3o e produ\u00e7\u00e3o), por exemplo, nomes conhecidos como Umberto Tavares, Rafinha RSQ e Anitta, mas tamb\u00e9m conterr\u00e2neos e amigos de Juliette como Juz\u00e9, Dann Costara e Toim do Gado.<\/p>\n\n\n\n<p>\u201cFoi um trabalho muito diferente do que eu j\u00e1 tinha feito (produzir esse projeto). Fizemos uma colabora\u00e7\u00e3o de artistas que estavam longe uns dos outros \u2013 em Miami, Salvador, Jo\u00e3o Pessoa e Rio de Janeiro, por exemplo. A sintonia e a vontade de todos de fazer um trabalho verdadeiro foi o que deu sentido e forma para esse EP\u201d, diz Juz\u00e9, paraibano amigo de longa data de Juliette e respons\u00e1vel pelo alinhamento musical de sua carreira.<\/p>\n\n\n\n<p>Nas letras do projeto est\u00e3o presentes temas como o amor, as dificuldades e prazeres da vida e a rela\u00e7\u00e3o de <a href=\"https:\/\/portalpopmais.com.br\/en\/letra-benca-juliette\/\" target=\"_blank\" data-type=\"post\" data-id=\"90996\" rel=\"noreferrer noopener\">Juliette<\/a> com as suas origens e a cultura nordestina.<\/p>\n\n\n\n<p>\u201cSempre gostei de m\u00fasica e de cantar. A arte tem um espa\u00e7o especial no meu cora\u00e7\u00e3o. \u00c9 uma emo\u00e7\u00e3o gigante criar esse projeto, meu primeiro, ao lado de pessoas t\u00e3o importantes e talentosas. Construir todo esse meu universo \u00e9 um sonho\u201d, diz Juliette.<\/p>\n\n\n\n<p>Segunda faixa da tracklist, \u201cDiferen\u00e7a Mara\u201d, foi a escolhida para ganhar um videoclipe, com dire\u00e7\u00e3o de ningu\u00e9m menos que Giovanni Bianco. O v\u00eddeo chega ao canal oficial de YouTube de Juliette no dia 6 de setembro, ao meio-dia.<\/p>\n\n\n\n<p>Ou\u00e7a:<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/album\/2QGcICCnguCa8ovMHUMs3q\" width=\"600\" height=\"380\" frameborder=\"0\" allowtransparency=\"true\" allow=\"encrypted-media\"><\/iframe>","protected":false},"excerpt":{"rendered":"<p>Chegou o grande dia! J\u00e1 est\u00e1 dispon\u00edvel em todas as plataformas digitais o primeiro EP de Juliette. O projeto foi desenvolvido como a primeira amostra musical da cantora e gravado entre as cidades do Rio de Janeiro, Salvador, Jo\u00e3o Pessoa e Recife. \u201cA m\u00fasica traduz sentimentos e d\u00e1 sentido \u00e0 vida. \u00c9 a fala da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":90997,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[2163,8135],"class_list":["post-91129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-capa","tag-juliette"],"_links":{"self":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/91129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/comments?post=91129"}],"version-history":[{"count":0,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/posts\/91129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media\/90997"}],"wp:attachment":[{"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/media?parent=91129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/categories?post=91129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalpopmais.com.br\/en\/wp-json\/wp\/v2\/tags?post=91129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}